{"id":10432,"date":"2022-09-21T08:00:39","date_gmt":"2022-09-21T13:00:39","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=10432"},"modified":"2022-09-21T08:02:34","modified_gmt":"2022-09-21T13:02:34","slug":"putin-declara-movilizacion-parcial-de-la-poblacion-rusa-para-la-guerra-en-ucrania","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2022\/09\/21\/putin-declara-movilizacion-parcial-de-la-poblacion-rusa-para-la-guerra-en-ucrania\/","title":{"rendered":"Putin declara \u201cmovilizaci\u00f3n parcial\u201d de la poblaci\u00f3n rusa a la guerra"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\"><em><strong>MOSC\u00da, RUSIA.<\/strong><\/em> El presidente de\u00a0Rusia,\u00a0<strong>Vladimir Putin<\/strong>, ha anunciado <strong>una\u00a0\u201cmovilizaci\u00f3n parcial\u201d de la poblaci\u00f3n\u00a0en plena\u00a0guerra en Ucrania<\/strong>, el mandatario destac\u00f3 que este decreto prev\u00e9 medidas adicionales en materia de adquisiciones estatales de defensa. <\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong><span style=\"font-size: 18pt; color: #139eca;\">\u00a0Vladimir Putin <\/span>ha explicado que las actividades relativas a esta movilizaci\u00f3n arrancar\u00e1n este mismo mi\u00e9rcoles y <span style=\"color: #139eca;\">ha resaltado que solo los reservistas, principalmente aquellos con experiencia y que hayan cumplido el servicio militar obligatorio, ser\u00e1n llamados a filas<\/span>. Antes de ser enviados a sus unidades, recibir\u00e1n entrenamiento adicional.\u00a0 Esta es la primera convocatoria en Rusia desde la Segunda Guerra Mundial.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10435 size-large\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA3-1024x573.png?resize=800%2C448&#038;ssl=1\" alt=\"\" width=\"800\" height=\"448\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA3.png?resize=1024%2C573&amp;ssl=1 1024w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA3.png?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA3.png?resize=768%2C430&amp;ssl=1 768w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA3.png?resize=1536%2C859&amp;ssl=1 1536w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA3.png?w=1816&amp;ssl=1 1816w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA3.png?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Me gustar\u00eda enfatizar que los ciudadanos rusos convocados al servicio militar en r\u00e9gimen de movilizaci\u00f3n recibir\u00e1n el estatus, los pagos y todas las garant\u00edas sociales de los militares que cumplen el servicio militar por contrato\u201d<\/span><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">As\u00ed, ha firmado un decreto presentado por el Ministerio de Defensa ruso con el objetivo de \u201cproteger Rusia, su soberan\u00eda e integridad territorial\u201d y ha hecho hincapi\u00e9 en que\u00a0los objetivos de la invasi\u00f3n de Ucrania \u201csiguen sin cambios\u201d. Tambi\u00e9n ha subray\u00f3 que los ciudadanos de Rusia pueden estar seguros de que la integridad territorial, la independencia y la libertad del pa\u00eds est\u00e1n garantizadas.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt; color: #139eca;\"><strong>EL OBJETIVO<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>En un mensaje televisado a la naci\u00f3n, el presidente ruso <span style=\"font-size: 18pt; color: #139eca;\">\u00a0Vladimir Putin <\/span>ha asegurado que\u00a0el <span style=\"color: #139eca;\">objetivo de Occidente es\u00a0\u201cdebilitar, dividir y destruir\u00a0finalmente\u201d<\/span> su pa\u00eds y ha agregado que los occidentales \u201cdicen abiertamente que en 1991 pudieron desmembrar la Uni\u00f3n Sovi\u00e9tica y que ahora ha llegado el turno de Rusia\u201d. En esta l\u00ednea <span style=\"color: #139eca;\">ha amenazado con usar \u201ctodos los medios disponibles\u201d y ha avisado de que aquellos que est\u00e1n tratando de usar el \u201cchantaje nuclear\u201d contra Rusia<\/span> encontrar\u00e1n que \u201cel viento podr\u00eda soplar en su direcci\u00f3n\u201d. No estoy mintiendo\u201d, ha alertado.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10434 size-large\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA2-1024x573.png?resize=800%2C448&#038;ssl=1\" alt=\"\" width=\"800\" height=\"448\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA2.png?resize=1024%2C573&amp;ssl=1 1024w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA2.png?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA2.png?resize=768%2C430&amp;ssl=1 768w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA2.png?resize=1536%2C859&amp;ssl=1 1536w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA2.png?w=1816&amp;ssl=1 1816w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA2.png?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Se trata no solo de los ataques alentados por Occidente contra la central nuclear de Zaporiyia, que pueden provocar una cat\u00e1strofe at\u00f3mica, sino tambi\u00e9n de las declaraciones de alto cargos de la OTAN acerca de la posibilidad en emplear contra Rusia armas de destrucci\u00f3n masiva\u201d<\/span><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Putin ha argumentado que las autoridades rusas \u201cno tienen derecho a dejar que la gente que vive en Ucrania, cerca de la frontera, sea\u00a0destrozada por ejecutores\u201d y ha prometido\u00a0apoyo a los refer\u00e9ndums anunciados por las autoridades prorrusas\u00a0de las autoproclamadas rep\u00fablicas populares de Donetsk, Lugansk y las regiones de Jers\u00f3n y Zaporiyia.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Asimismo, ha destacado que las fuerzas rusas presentes en Ucrania operan a lo largo de una\u00a0l\u00ednea de contacto de m\u00e1s de mil kil\u00f3metros\u00a0y ha afirmado que hacen frente \u201ca toda la maquinaria militar occidental\u201d, tal y como ha recogido la agencia rusa de noticias Interfax.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>El Kremlin public\u00f3 el decreto sobre la movilizaci\u00f3n parcial en la Federaci\u00f3n de Rusia. El decreto entra en vigor desde el mismo 21 de septiembre.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; MOSC\u00da, RUSIA. El presidente de\u00a0Rusia,\u00a0Vladimir Putin, ha anunciado una\u00a0\u201cmovilizaci\u00f3n parcial\u201d de la poblaci\u00f3n\u00a0en plena\u00a0guerra en Ucrania, el mandatario destac\u00f3<\/p>\n","protected":false},"author":4,"featured_media":10433,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[1489,1488,74,77],"class_list":["post-10432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-militar","tag-movilizacion-parcial","tag-rusia","tag-vladimir-putin"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-MOVILIZACIO%CC%81N-PARCIAL-RUSA1.png?fit=1816%2C1016&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10432"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/10433"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}