{"id":11251,"date":"2022-10-11T16:34:28","date_gmt":"2022-10-11T21:34:28","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=11251"},"modified":"2022-10-11T16:45:41","modified_gmt":"2022-10-11T21:45:41","slug":"famosa-sonoridad-wagneriana-la-octava-de-bruckner-llega-a-la-osx","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2022\/10\/11\/famosa-sonoridad-wagneriana-la-octava-de-bruckner-llega-a-la-osx\/","title":{"rendered":"Famosa sonoridad Wagneriana, la \u201cOctava\u201d de Bruckner llega a la OSX"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>&lt;&lt; 98 m\u00fasicos conforman la dotaci\u00f3n para la obra &gt;&gt;<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>&lt;&lt;Martin Lebel, Director Titular &gt;&gt;<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\"><em><strong>XALAPA, VERACRUZ.<\/strong> <\/em>La <strong>Orquesta Sinf\u00f3nica de Xalapa (OSX) de la Universidad Veracruzana (UV)<\/strong>, presenta en Tlaqn\u00e1, Centro Cultural, una de las obras m\u00e1s aclamadas a nivel mundial: <span style=\"color: #139eca; font-size: 18pt;\"><strong>\u201cSinfon\u00eda No. 8\u201d de Anton Bruckner. <\/strong><\/span>Pieza central en el vasto repertorio del compositor austr\u00edaco que involucra un amplio grupo orquestal y la utilizaci\u00f3n de las famosas: Tubas Wagnerianas. <\/span><span style=\"font-size: 18pt; color: #139eca;\"><strong>Bajo la direcci\u00f3n de Martin Lebel, Director Titular.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Este concierto ser\u00e1 realizado el viernes 14 de octubre a las 20:30 hrs. desde Tlaqn\u00e1, Centro Cultural. Asiste a la Charla previa a realizarse desde el Lobby de Tlaqn\u00e1 a las 19:30 hrs.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11252 size-large\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/10\/P-OCTAVA-OSX-1-1024x573.png?resize=800%2C448&#038;ssl=1\" alt=\"\" width=\"800\" height=\"448\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/10\/P-OCTAVA-OSX-1.png?resize=1024%2C573&amp;ssl=1 1024w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/10\/P-OCTAVA-OSX-1.png?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/10\/P-OCTAVA-OSX-1.png?resize=768%2C430&amp;ssl=1 768w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/10\/P-OCTAVA-OSX-1.png?resize=1536%2C859&amp;ssl=1 1536w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/10\/P-OCTAVA-OSX-1.png?w=1816&amp;ssl=1 1816w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/10\/P-OCTAVA-OSX-1.png?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt; color: #139eca;\"><strong>MONUMENTAL OCTAVA<\/strong><\/span><br \/>\n<span style=\"font-size: 18pt;\"><strong>La \u201cSinfon\u00eda No. 8\u201d es sin lugar a dudas una de las obras m\u00e1s importantes del grandilocuente compositor Anton Bruckner, dentro de su estudiado y aclamado repertorio, la monumental \u201coctava\u201d estremece y regocija al p\u00fablico mel\u00f3mano en todo el mundo. <span style=\"color: #139eca;\">De sonoridad Wagneriana y estructura Beethoveniana, fue estrenada en v\u00edsperas de navidad desde Viena en 1892 por Hans Richter, gozando de un \u00e9xito a\u00fan mayor que su predecesora (la famosa s\u00e9ptima).<\/span><\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Tras tres a\u00f1os de arduo trabajo entre 1884-1887, y la decepci\u00f3n que le gener\u00f3 el director de orquesta Hermann Levi a Bruckner tras negarse a estrenarla; esta obra fue revisada al punto de generar tres versiones diferentes debido a la necesidad de perfeccionismo del autor y la desmedida atenci\u00f3n que pon\u00eda a las cr\u00edticas a su trabajo.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Esta obra es vasta en contenido y riqueza sonora, expuesta de manera compacta a pesar de su duraci\u00f3n. Bajo su estructura de cuatro movimientos, desarrolla de forma magn\u00edfica intensidad insospechada y gloriosas armon\u00edas a trav\u00e9s de los oscuros y vibrantes sonidos de metales bajos como las tubas wagnerianas.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Desgarradora, sublime y majestuosa obra que abraza la perfecci\u00f3n y posee un lugar especial en la historia musical.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Los boletos podr\u00e1n ser adquiridos en Tienda UV (a un costado de la Facultad de Contadur\u00eda y Administraci\u00f3n, Zona UV, de 10:00 a 15:00 y de 16:00 a 18:00 hrs.) y en Taquilla Tlaqn\u00e1 el d\u00eda del evento a partir de las 11:00 hrs. y hasta agotar existencias.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>A su vez tambi\u00e9n podr\u00e1 encontrarlos en el sitio web: <a href=\"http:\/\/www.orquestasinfonicadexalapa.com\">www.orquestasinfonicadexalapa.com<\/a><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &lt;&lt; 98 m\u00fasicos conforman la dotaci\u00f3n para la obra &gt;&gt; &lt;&lt;Martin Lebel, Director Titular &gt;&gt; &nbsp; XALAPA, VERACRUZ. La<\/p>\n","protected":false},"author":4,"featured_media":11253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[474],"tags":[1613,1612,837,772,1611,823,451],"class_list":["post-11251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-anton-bruckner","tag-martin-lebel","tag-orquesta-sinfonica-de-xalapa","tag-osx","tag-sinfonia-n-8","tag-universidad-veracruzana","tag-uv"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/10\/P-OCTAVA-OSX-2.png?fit=1816%2C1016&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=11251"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/11251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/11253"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=11251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=11251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=11251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}