{"id":1152,"date":"2021-12-29T14:47:14","date_gmt":"2021-12-29T20:47:14","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=1152"},"modified":"2023-04-10T14:00:05","modified_gmt":"2023-04-10T19:00:05","slug":"raptan-y-asesinan-a-hija-de-12-anos-de-alcalde-de-xoxocotla","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2021\/12\/29\/raptan-y-asesinan-a-hija-de-12-anos-de-alcalde-de-xoxocotla\/","title":{"rendered":"Raptan y asesinan a hija de 12 a\u00f1os de alcalde de Xoxocotla"},"content":{"rendered":"<p class=\"p1\"><strong>ZONGOLICA.<\/strong> <strong>Encuentran el cuerpo sin vida de la hija del alcalde de Xoxocotla<\/strong>, Magdaleno Ju\u00e1rez P\u00e9rez, <strong>ten\u00eda s\u00f3lo 12 a\u00f1os fue raptada y asesinada. <\/strong><\/p>\n<p class=\"p1\"><strong>El cad\u00e1ver<\/strong> fue descubierto en el tramo Xoxocotla a Soledad Atzompa ubicado en la sierra de Zongolica en Veracruz <strong>en la comunidad La Mesita<\/strong>, fueron <strong>vecinos del lugar quienes reportaron el hecho a las autoridades estatales.<\/strong><\/p>\n<p class=\"p1\">Cabe destacar que cerca del fatal escenario <strong>se encontr\u00f3 un coche con un hombre<\/strong> en el interior, el cual fue trasladado al nosocomio <strong>inconsciente y herido de gravedad<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_1153\" aria-describedby=\"caption-attachment-1153\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-1153\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2021\/12\/COCHE1-300x168.png?resize=600%2C336&#038;ssl=1\" alt=\"\" width=\"600\" height=\"336\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2021\/12\/COCHE1.png?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2021\/12\/COCHE1.png?resize=1024%2C573&amp;ssl=1 1024w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2021\/12\/COCHE1.png?resize=768%2C430&amp;ssl=1 768w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2021\/12\/COCHE1.png?resize=1536%2C859&amp;ssl=1 1536w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2021\/12\/COCHE1.png?w=1816&amp;ssl=1 1816w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2021\/12\/COCHE1.png?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-1153\" class=\"wp-caption-text\">Veh\u00edculo donde fue encontrado el joven herido.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><strong>LOS HECHOS<\/strong><\/p>\n<p class=\"p1\">Los hechos se suscitaron el pasado lunes en la noche, la\u00a0menor de 12 a\u00f1os\u00a0fue sacada de un festejo organizado por su padre, el alcalde, quien as\u00ed cerraba su periodo en la presidencia municipal.<\/p>\n<p class=\"p1\"><strong>Algunos reportes se\u00f1alaron que la menor de edad presentaba abuso sexual y signos de violencia.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><strong>REACCIONES<\/strong><\/p>\n<p class=\"p1\">Tras la noticia diversos actores pol\u00edticos del estado enviaron sus mensajes de consternaci\u00f3n ante lamentable evento.<\/p>\n<blockquote>\n<p class=\"p1\">Desgraciadamente vivimos en una sociedad enferma, llena de odio, inconsciencia y maldad, una sociedad podrida, sin valores, sin escr\u00fapulos\u201d, escribi\u00f3 Her\u00f3n Ver\u00f3nica, de la Secretar\u00eda de Desarrollo Agropecuario, Rural y Pesca de Veracruz, en un mensaje en Facebook.<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><strong>En tanto la Diputada Anil\u00fa Ingram Vallines expres\u00f3 su indignaci\u00f3n por \u201cel terrible presunto feminicidio de la hija del Alcalde de Xoxocotla\u201d.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Expres\u00e9 nuestra indignaci\u00f3n por el terrible presunto feminicidio de la hija del alcalde de Xoxocotla. <\/p>\n<p>Una ni\u00f1a de tan solo 12 a\u00f1os que no ten\u00eda que morir y mucho menos de esa forma. <\/p>\n<p>Exigimos justicia y acciones de verdad para ya no tener estos aberrantes hechos. <a href=\"https:\/\/twitter.com\/GLPRI_VER?ref_src=twsrc%5Etfw\">@GLPRI_VER<\/a> <a href=\"https:\/\/t.co\/S0JHQ0yp70\">pic.twitter.com\/S0JHQ0yp70<\/a><\/p>\n<p>&mdash; Anilu Ingram (@AniluIngram) <a href=\"https:\/\/twitter.com\/AniluIngram\/status\/1476021799674593281?ref_src=twsrc%5Etfw\">December 29, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p class=\"p1\">Conf\u00edo en que las autoridades hagan su trabajo y realicen las investigaciones correspondientes que lleven hasta los responsables por tan reprobable y condenable hecho\u201d, coment\u00f3 el Diputado Luis Arturo Santiago Mart\u00ednez.<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ZONGOLICA. Encuentran el cuerpo sin vida de la hija del alcalde de Xoxocotla, Magdaleno Ju\u00e1rez P\u00e9rez, ten\u00eda s\u00f3lo 12 a\u00f1os<\/p>\n","protected":false},"author":1,"featured_media":1154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30],"tags":[212,211,210,100,209],"class_list":["post-1152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados","tag-alcalde","tag-feminicidio","tag-hija","tag-veracruz","tag-xoxocotla"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2021\/12\/COCHE2.png?fit=1816%2C1016&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1152"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/1154"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}