{"id":12576,"date":"2022-11-15T06:00:58","date_gmt":"2022-11-15T12:00:58","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=12576"},"modified":"2022-11-15T09:26:04","modified_gmt":"2022-11-15T15:26:04","slug":"ley-contra-el-poder","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2022\/11\/15\/ley-contra-el-poder\/","title":{"rendered":"Ley contra el poder"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><span style=\"font-size: 18pt;\"><strong>Por Alberto Woolrich Ort\u00edz<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">En la actualidad los se\u00f1ores jueces, magistrados y ministros de la Suprema Corte de Justicia de la Naci\u00f3n, que son decentes, tienen un papel dif\u00edcil. Nada envidiable. Impartir justicia en \u00e9sta Cuarta Transformaci\u00f3n de la Naci\u00f3n, para ellos, resulta ser<span class=\"Apple-converted-space\">\u00a0 <\/span>complicad\u00edsimo.<span class=\"Apple-converted-space\">\u00a0 <\/span>Dejar satisfecho al Poder Ejecutivo imposible. Para la Abogac\u00eda Independiente de la Rep\u00fablica, obligado es rendir tributo a tantas togas de impartici\u00f3n de justicia que ejercen su ministerio con la mayor probidad e inter\u00e9s en obsequiarla libre de presiones pol\u00edticas o jer\u00e1rquicas.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Me dec\u00eda en pasadas horas un ministro de la Suprema Corte de Justicia de la Naci\u00f3n que existen togas de indignidad que no respetan la verdadera esencia de nuestro Pacto Federal; la Academia de Derecho Penal del Colegio Nacional de Abogados de M\u00e9xico Foro Independiente, estima que en la actualidad hay ciertos problemas por los que atraviesa nuestra Rep\u00fablica y que no son, principalmente,<span class=\"Apple-converted-space\">\u00a0 <\/span>problemas de derecho, sino injerencias del Poder Ejecutivo en la Justicia. Nuestra Carta Magna reside y tiene valor al expresar fielmente los factores imperantes de la realidad social y pol\u00edtica y esa m\u00e1xima ley se opone a esas necedades. La esencia de la ley es que se le respete.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Es interesante percatarse que en la actualidad existe una confronta entre la aplicaci\u00f3n de la Norma Constitucional y el poder emanado de la Cuarta Transformaci\u00f3n de la Naci\u00f3n. Nuestra Suprema Ley, como es sabido, no siempre se aplica.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">En las circunstancias actuales por las que vive M\u00e9xico, la intervenci\u00f3n de Andr\u00e9s Manuel L\u00f3pez Obrador y muchos de sus corifeos trastocan la vida jur\u00eddica al inmiscuir la pol\u00edtica en ella; es indudable que lo proclamado en el Texto Constitucional es el primer paso para poner obst\u00e1culos<span class=\"Apple-converted-space\">\u00a0 <\/span>a esas m\u00faltiples injerencias propiciadas por esas incorrectas intervenciones. El Pacto Federal es m\u00e1s influyente y tiende a modificar ese incorrecta forma de pensar y actuar.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Los grandes constitucionalistas de la Rep\u00fablica; explican con profundidad la sustancia y esencia de nuestra Ley de Leyes; alguno de ellos, como Alfonso Jim\u00e9nez O\u2019farril, describen la evoluci\u00f3n pol\u00edtico social de la Cuarta Transformaci\u00f3n de la Naci\u00f3n que pretende llevarnos a un Estado absolutista, dominante de la sociedad, a un Estado totalitarista, con argumentos inoperantes que intentan la Supremac\u00eda Militar en contra de lo que refiere la esencia de nuestro Pacto Federal.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">A esos hombres del poder arbitrario, la Abogac\u00eda Independiente de la Rep\u00fablica, les hace saber, que nuestro Texto Constitucional es un documento solemne integrado con Normas Jur\u00eddicas de tendencia permanente y ese esp\u00edritu y esencia impide y va a impedir ese tipo de intromisiones que afectan a nuestra Ley Suprema.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Esa es la esencia de la Carta de Carranza. Esa es la ley que va a triunfar contra ese poder de disipaci\u00f3n.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Es por todo ello que impartir justicia en la vida actual, resulta ser complicad\u00edsimo, sin embargo cabe afirmar que al final de cuentas la ley va a triunfar en contra de cualquier poder por arbitrario o ignorante que pueda ser. Es cuanto.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><strong><span style=\"font-size: 18pt;\">Lic. Alberto Woolrich Ort\u00edz<\/span><\/strong><\/p>\n<p class=\"p1\"><strong><span style=\"font-size: 18pt;\">Presidente de la Academia de Derecho Penal<\/span><\/strong><\/p>\n<p class=\"p1\"><strong><span style=\"font-size: 18pt;\">del Colegio de Abogados de M\u00e9xico, A.C.<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 18pt; color: #139eca;\"><em><strong>**Las columnas firmadas en este medio son responsabilidad de quienes las firman**<\/strong><\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Por Alberto Woolrich Ort\u00edz En la actualidad los se\u00f1ores jueces, magistrados y ministros de la Suprema Corte de Justicia<\/p>\n","protected":false},"author":4,"featured_media":3845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26],"tags":[],"class_list":["post-12576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/CABEZAL-ALBERTO-WOOD.png?fit=1816%2C1016&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=12576"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3845"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=12576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=12576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=12576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}