{"id":20967,"date":"2023-06-12T04:07:11","date_gmt":"2023-06-12T09:07:11","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=20967"},"modified":"2023-06-12T12:45:41","modified_gmt":"2023-06-12T17:45:41","slug":"para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/","title":{"rendered":"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: center;\"><em><span style=\"font-size: 18pt;\"><b>&lt;&lt;Para 2024 la pugna por la candidatura ser\u00e1 la lucha por la gubernatura ante una oposici\u00f3n d\u00e9bil&gt;&gt;<\/b><\/span><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: left;\"><span style=\"font-size: 18pt;\"><b>Por \u00c1ngel \u00c1lvaro Pe\u00f1a<\/b><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">La efervescencia pol\u00edtica y social en donde se renovar\u00e1 gobernador en 2024, crece cada d\u00eda. Chiapas, Guanajuato, Jalisco, Morelos, Puebla, Tabasco, Veracruz, Yucat\u00e1n y Ciudad de M\u00e9xico, deber\u00e1n escoger mandatario estatal, donde la Ciudad de M\u00e9xico, Jalisco y Veracruz representan casi el mismo n\u00famero de habitantes que el resto de las entidades en contienda electoral.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Como sucede con la Presidencia de la Rep\u00fablica, donde el candidato opositor s\u00f3lo servir\u00e1 como requisito burocr\u00e1tico en la contienda electoral, en Veracruz, Morena tiene asegurado el triunfo.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">De ah\u00ed que los ojos del pa\u00eds volteen a ver a Veracruz y su sucesi\u00f3n gubernamental, donde algunos ponen a una multitud a concursar cuando en realidad son dos o tres personas las concursantes y una sola al que tiene posibilidades de triunfo.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt; color: #139eca;\"><strong>Pero mientras m\u00e1s personajes suelten para la contienda de la candidatura por morena es m\u00e1s f\u00e1cil colar a los improvisados y debe resaltar lo mal que se ve el secretario de Gobernaci\u00f3n, Ad\u00e1n Augusto L\u00f3pez Hern\u00e1ndez, promocionando a su chamaco Sergio Guti\u00e9rrez Luna, con quien carga cada vez que visita la entidad, o se le pega el diputado a el secretario lo llama a acompa\u00f1arlo. Lo cierto es que, desde el mitin en el Estado de M\u00e9xico, donde se llam\u00f3 a la unidad en la ciudad de Toluca, Sergio Guti\u00e9rrez Luna, apareci\u00f3 sorpresivamente en el evento impulsando una candidatura en especial.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20969 size-large\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-2-1024x573.png?resize=800%2C448&#038;ssl=1\" alt=\"\" width=\"800\" height=\"448\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-2.png?resize=1024%2C573&amp;ssl=1 1024w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-2.png?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-2.png?resize=768%2C430&amp;ssl=1 768w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-2.png?resize=1536%2C859&amp;ssl=1 1536w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-2.png?w=1816&amp;ssl=1 1816w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Hace un a\u00f1o exactamente. El 12 de junio en el mitin en el Teatro Morelos de la capital mexiquense se reunieron militantes y simpatizantes de Morena para convocar a la unidad, al tiempo que se presentaban los entonces tres \u00fanicos aspirantes a la Presidencia de la Rep\u00fablica por ese partido: Claudia, Marcelo y Ad\u00e1n Augusto, que son los punteros en las encuestas recientes.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt; color: #139eca;\"><strong>Esa fue la primera vez que se ve\u00edan playeras con la imagen de Ad\u00e1n augusto, y que fueron repartidas a diestra y siniestra en el evento, incluso algunos asistentes llegaron a rechazarlas por no coincidir con esta propuesta electoral hacia la candidatura.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">A un a\u00f1o de esta reuni\u00f3n que invitaba a la unidad, el secretario de Gobernaci\u00f3n, quien parec\u00eda el menos protag\u00f3nico, ahora comparte una pasarela en cada visita a Veracruz con Sergio Guti\u00e9rrez Luna, es un diputado\u00a0federal por el Estado de M\u00e9xico y expresidente de la Mesa Directiva en San L\u00e1zaro, quien se ha declarado listo para buscar la candidatura de Morena a la gubernatura de Veracruz. El chamaco imberbe afirma que es el \u00fanico que lo ha dicho de frente y que conf\u00eda en que ganar\u00e1 el proceso interno y la elecci\u00f3n, todo porque hizo un papel de dique de contenci\u00f3n en el INE representando a Morena en tiempos del inefable Lorenzo C\u00f3rdova.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">No sabe que lleg\u00f3 a una larga fila de militantes de su partido que bien podr\u00edan hacer mejor papel que \u00e9l, y no porque sea tonto sino porque est\u00e1 muy verde para una responsabilidad de esa magnitud.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt; color: #139eca;\"><b>M\u00c1S CORCHOLATAS<\/b><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Por s\u00f3lo nombrar a algunos est\u00e1n delante de \u00e9l, Roc\u00edo Nahle, Ricardo Ahued, Manuel Huerta, entre otros de segunda divisi\u00f3n dentro de Morena. De la oposici\u00f3n hay poco qu\u00e9 decir.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Hace un par de d\u00edas\u00a0un joven irrumpi\u00f3 en un evento del presidente\u00a0Andr\u00e9s Manuel L\u00f3pez Obrador\u00a0para pedir que apoyar\u00e1 las aspiraciones presidenciales del titular de Gobernaci\u00f3n. Casualmente esto sucedi\u00f3 en\u00a0Veracruz y\u00a0previo al\u00a0Consejo Nacional de Morena, el cual aprobar\u00eda la encuesta para definir al candidato presidencial.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Sergio envi\u00f3 al joven a interrumpir el discurso del Presidente para apoyar a Ad\u00e1n Augusto, as\u00ed como pago las playeras aquel 12 de junio de 2022.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt; color: #139eca;\"><strong>Sergio Guti\u00e9rrez considera que basta con el apoyo de Ad\u00e1n Augusto para posicionarse como el pr\u00f3ximo candidato a la gubernatura de Veracruz. Ad\u00e1n Augusto tiene un jefe muy poderoso que debe obedecer y la conducta de Guti\u00e9rrez es muy indisciplinada.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Sergio Guti\u00e9rrez Luna pareciera tambi\u00e9n actuar por su cuenta en pro de la promoci\u00f3n de su imagen hacia la gubernatura. De vez en cuando invita a algunos periodistas a desayunar a quienes regala un desayuno, sus ya famosas playeras en favor de Ad\u00e1n Augusto, entre otras cosas.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Pide que le digan \u201cCheco\u201d y que lo traten de igual a igual. Es bueno tener proyectos pero no irrumpir en un orden establecido en nombre de la ambici\u00f3n, montado en la posible candidatura de Ad\u00e1n Augusto.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20970 size-large\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-3-1024x573.png?resize=800%2C448&#038;ssl=1\" alt=\"\" width=\"800\" height=\"448\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-3.png?resize=1024%2C573&amp;ssl=1 1024w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-3.png?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-3.png?resize=768%2C430&amp;ssl=1 768w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-3.png?resize=1536%2C859&amp;ssl=1 1536w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-3.png?w=1816&amp;ssl=1 1816w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Pero de d\u00f3nde le vienen esos aires de grandeza al diputado Guti\u00e9rrez, sucede que cuando hubo la consulta sobre la revocaci\u00f3n de mandato, era presidente de la Mesa Directiva de la C\u00e1mara de Diputados y seg\u00fan la Ley Federal de Revocaci\u00f3n de Mandato del 14 de septiembre, se\u00f1ala que\u00a0\u00a0en el caso de que la falta del\u00a0Presidente de la Rep\u00fablica\u00a0ocurriese tras una revocaci\u00f3n de mandato, la constituci\u00f3n se\u00f1ala que quien ocupe la presidencia del\u00a0Congreso; dentro de los treinta d\u00edas siguientes, ese personaje era \u00e9l, convirti\u00e9ndose en presidente interino de M\u00e9xico.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Sergio Guti\u00e9rrez Luna es abogado egresado de la Escuela Libre de Derecho, cuenta con diplomados en\u00a0Proceso Penal Acusatorio y Oral y en Delitos Fiscales\u00a0y con estudios en curso de maestr\u00eda en\u00a0Derecho Constitucional, pero tambi\u00e9n tiene sus pecados mortales, entre 1998 y 1999 fue asesor en la\u00a0Coordinaci\u00f3n Central de Recursos del Sistema de Administraci\u00f3n Tributaria, de 2000 a 2003 en el sexenio de Vicente Fox.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt; color: #139eca;\"><strong>A pesar de la edad de Guti\u00e9rrez Luna, de su poca experiencia en la pol\u00edtica, tiene su pasado oscuro que no lo hace morenista qu\u00edmicamente puro.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &lt;&lt;Para 2024 la pugna por la candidatura ser\u00e1 la lucha por la gubernatura ante una oposici\u00f3n d\u00e9bil&gt;&gt; &nbsp; &nbsp; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[33],"tags":[1394,431,63,2847,100],"class_list":["post-20967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-adan-augusto","tag-gubernatura","tag-morena","tag-sergio-guierrez","tag-veracruz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz - Pol\u00edticos al Desnudo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz - Pol\u00edticos al Desnudo\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &lt;&lt;Para 2024 la pugna por la candidatura ser\u00e1 la lucha por la gubernatura ante una oposici\u00f3n d\u00e9bil&gt;&gt; &nbsp; &nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/\" \/>\n<meta property=\"og:site_name\" content=\"Pol\u00edticos al Desnudo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PoliticosAD\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T09:07:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T17:45:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-1-1024x573.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n Pol\u00edticos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n Pol\u00edticos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n Pol\u00edticos\",\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/#\\\/schema\\\/person\\\/ef3a64e561cc3f3f5dc52fab81adde7e\"},\"headline\":\"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz\",\"datePublished\":\"2023-06-12T09:07:11+00:00\",\"dateModified\":\"2023-06-12T17:45:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/\"},\"wordCount\":1027,\"publisher\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/politicosaldesnudo.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/P-SERGIO-GTZ-VERACRUZ-1.png?fit=1816%2C1016&ssl=1\",\"keywords\":[\"ADAN AUGUSTO\",\"GUBERNATURA\",\"MORENA\",\"SERGIO GUIERREZ\",\"VERACRUZ\"],\"articleSection\":[\"NACIONAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/\",\"url\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/\",\"name\":\"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz - Pol\u00edticos al Desnudo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/politicosaldesnudo.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/P-SERGIO-GTZ-VERACRUZ-1.png?fit=1816%2C1016&ssl=1\",\"datePublished\":\"2023-06-12T09:07:11+00:00\",\"dateModified\":\"2023-06-12T17:45:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/politicosaldesnudo.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/P-SERGIO-GTZ-VERACRUZ-1.png?fit=1816%2C1016&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/politicosaldesnudo.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/P-SERGIO-GTZ-VERACRUZ-1.png?fit=1816%2C1016&ssl=1\",\"width\":1816,\"height\":1016},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/2023\\\/06\\\/12\\\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/\",\"name\":\"Pol\u00edticos al Desnudo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/#organization\",\"name\":\"Pol\u00edticos al Desnudo\",\"url\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/politicosaldesnudo.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/cropped-logo.webp?fit=400%2C126&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/politicosaldesnudo.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/cropped-logo.webp?fit=400%2C126&ssl=1\",\"width\":400,\"height\":126,\"caption\":\"Pol\u00edticos al Desnudo\"},\"image\":{\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PoliticosAD\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/#\\\/schema\\\/person\\\/ef3a64e561cc3f3f5dc52fab81adde7e\",\"name\":\"Redacci\u00f3n Pol\u00edticos\",\"url\":\"https:\\\/\\\/politicosaldesnudo.com.mx\\\/index.php\\\/author\\\/redaccion-politicos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz - Pol\u00edticos al Desnudo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/","og_locale":"es_ES","og_type":"article","og_title":"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz - Pol\u00edticos al Desnudo","og_description":"&nbsp; &lt;&lt;Para 2024 la pugna por la candidatura ser\u00e1 la lucha por la gubernatura ante una oposici\u00f3n d\u00e9bil&gt;&gt; &nbsp; &nbsp; [&hellip;]","og_url":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/","og_site_name":"Pol\u00edticos al Desnudo","article_publisher":"https:\/\/www.facebook.com\/PoliticosAD","article_published_time":"2023-06-12T09:07:11+00:00","article_modified_time":"2023-06-12T17:45:41+00:00","og_image":[{"width":1024,"height":573,"url":"https:\/\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-1-1024x573.png","type":"image\/png"}],"author":"Redacci\u00f3n Pol\u00edticos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n Pol\u00edticos","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/#article","isPartOf":{"@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/"},"author":{"name":"Redacci\u00f3n Pol\u00edticos","@id":"https:\/\/politicosaldesnudo.com.mx\/#\/schema\/person\/ef3a64e561cc3f3f5dc52fab81adde7e"},"headline":"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz","datePublished":"2023-06-12T09:07:11+00:00","dateModified":"2023-06-12T17:45:41+00:00","mainEntityOfPage":{"@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/"},"wordCount":1027,"publisher":{"@id":"https:\/\/politicosaldesnudo.com.mx\/#organization"},"image":{"@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-1.png?fit=1816%2C1016&ssl=1","keywords":["ADAN AUGUSTO","GUBERNATURA","MORENA","SERGIO GUIERREZ","VERACRUZ"],"articleSection":["NACIONAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/","url":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/","name":"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz - Pol\u00edticos al Desnudo","isPartOf":{"@id":"https:\/\/politicosaldesnudo.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/#primaryimage"},"image":{"@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-1.png?fit=1816%2C1016&ssl=1","datePublished":"2023-06-12T09:07:11+00:00","dateModified":"2023-06-12T17:45:41+00:00","breadcrumb":{"@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/#primaryimage","url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-1.png?fit=1816%2C1016&ssl=1","contentUrl":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-1.png?fit=1816%2C1016&ssl=1","width":1816,"height":1016},{"@type":"BreadcrumbList","@id":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/06\/12\/para-que-tantos-brincos-lecciones-y-elecciones-en-veracruz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/politicosaldesnudo.com.mx\/"},{"@type":"ListItem","position":2,"name":"Para qu\u00e9 tantos brincos\u2026 Lecciones y elecciones en Veracruz"}]},{"@type":"WebSite","@id":"https:\/\/politicosaldesnudo.com.mx\/#website","url":"https:\/\/politicosaldesnudo.com.mx\/","name":"Pol\u00edticos al Desnudo","description":"","publisher":{"@id":"https:\/\/politicosaldesnudo.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/politicosaldesnudo.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/politicosaldesnudo.com.mx\/#organization","name":"Pol\u00edticos al Desnudo","url":"https:\/\/politicosaldesnudo.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/politicosaldesnudo.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/cropped-logo.webp?fit=400%2C126&ssl=1","contentUrl":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/cropped-logo.webp?fit=400%2C126&ssl=1","width":400,"height":126,"caption":"Pol\u00edticos al Desnudo"},"image":{"@id":"https:\/\/politicosaldesnudo.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PoliticosAD"]},{"@type":"Person","@id":"https:\/\/politicosaldesnudo.com.mx\/#\/schema\/person\/ef3a64e561cc3f3f5dc52fab81adde7e","name":"Redacci\u00f3n Pol\u00edticos","url":"https:\/\/politicosaldesnudo.com.mx\/index.php\/author\/redaccion-politicos\/"}]}},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":88247,"url":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/08\/31\/pepe-yunes-frena-rumores-de-ruptura-con-el-pri-y-se-ofrece-para-unir-a-la-oposicion-en-veracruz\/","url_meta":{"origin":20967,"position":0},"title":"Pepe Yunes frena rumores de ruptura con el PRI y se ofrece para unir a la oposici\u00f3n en Veracruz","author":"Redacci\u00f3n Pol\u00edticos","date":"31 de agosto de 2026","format":false,"excerpt":"Su aparici\u00f3n en un encuentro de Movimiento Ciudadano aliment\u00f3 las versiones sobre un posible cambio de partido. El excandidato a gobernador asegur\u00f3 que seguir\u00e1 en el tricolor, pero buscar\u00e1 construir un bloque amplio contra Morena rumbo a 2027. Xalapa, Ver.\u2014 Jos\u00e9 Francisco Yunes Zorrilla puso freno a las especulaciones sobre\u2026","rel":"","context":"En \u00abESTADOS\u00bb","block_context":{"text":"ESTADOS","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/category\/estados\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pepe-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pepe-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pepe-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pepe-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pepe-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":87964,"url":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/08\/22\/veracruz-segundo-lugar-nacional-en-hallazgo-de-fosas-clandestinas-durante-18-anos\/","url_meta":{"origin":20967,"position":1},"title":"Veracruz, segundo lugar nacional en hallazgo de fosas clandestinas durante 18 a\u00f1os","author":"Redacci\u00f3n Pol\u00edticos","date":"22 de agosto de 2026","format":false,"excerpt":"La crisis de desapariciones mantiene a Veracruz entre las entidades m\u00e1s afectadas del pa\u00eds. Una investigaci\u00f3n de la Universidad Iberoamericana document\u00f3 400 fosas clandestinas en territorio veracruzano entre 2006 y 2024, cifra solamente superada por las 416 registradas en Guerrero. El estudio, denominado Trazar la ausencia, caminar la esperanza, fue\u2026","rel":"","context":"En \u00abESTADOS\u00bb","block_context":{"text":"ESTADOS","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/category\/estados\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/1032178c-d889-4e44-a3ee-6e46cf6aeb79.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/1032178c-d889-4e44-a3ee-6e46cf6aeb79.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/1032178c-d889-4e44-a3ee-6e46cf6aeb79.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/1032178c-d889-4e44-a3ee-6e46cf6aeb79.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/1032178c-d889-4e44-a3ee-6e46cf6aeb79.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":87950,"url":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/08\/21\/pan-abre-la-puerta-a-pactos-con-el-pri-en-veracruz-rumbo-a-2027\/","url_meta":{"origin":20967,"position":2},"title":"PAN abre la puerta a pactos con el PRI en Veracruz rumbo a 2027","author":"Redacci\u00f3n Pol\u00edticos","date":"21 de agosto de 2026","format":false,"excerpt":"La posibilidad de que el PAN y el PRI vuelvan a competir juntos en Veracruz no est\u00e1 completamente descartada. La dirigencia nacional de Acci\u00f3n Nacional evaluar\u00e1 cada distrito antes de decidir si establece acuerdos electorales para los comicios de 2027. Durante una visita a la entidad, el presidente nacional del\u2026","rel":"","context":"En \u00abESTADOS\u00bb","block_context":{"text":"ESTADOS","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/category\/estados\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pan-pri.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pan-pri.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pan-pri.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pan-pri.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/pan-pri.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":88214,"url":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/08\/31\/pepe-yunes-el-mil-chaquetas\/","url_meta":{"origin":20967,"position":3},"title":"Pepe Yunes: El mil chaquetas","author":"Redacci\u00f3n Pol\u00edticos","date":"31 de agosto de 2026","format":false,"excerpt":"PRIMICIAS Por Vicente Mart\u00ednez Pepe Yunes volvi\u00f3 a aparecer en la escena pol\u00edtica veracruzana y su presencia en la asamblea de Movimiento Ciudadano, realizada este domingo en el puerto, ya despert\u00f3 lecturas rumbo al 2030. Al priista le han puesto el mote de \u201cel mil chaquetas\u201d por su capacidad para\u2026","rel":"","context":"En \u00abOPINI\u00d3N\u00bb","block_context":{"text":"OPINI\u00d3N","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/category\/columnistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/vicente-3108.png?fit=1200%2C658&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/vicente-3108.png?fit=1200%2C658&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/vicente-3108.png?fit=1200%2C658&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/vicente-3108.png?fit=1200%2C658&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/vicente-3108.png?fit=1200%2C658&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":88217,"url":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/08\/31\/morena-aprieta-filas-en-veracruz\/","url_meta":{"origin":20967,"position":4},"title":"Morena aprieta filas en Veracruz","author":"Redacci\u00f3n Pol\u00edticos","date":"31 de agosto de 2026","format":false,"excerpt":"ALMA GRANDE Por \u00c1ngel \u00c1lvaro Pe\u00f1a La pol\u00edtica veracruzana empieza a calentarse en las estructuras de Morena. Una asamblea de Comit\u00e9s de Organizaci\u00f3n Territorial y presidentes seccionales dej\u00f3 ver que el movimiento ya est\u00e1 preparando m\u00fasculo pol\u00edtico para los siguientes escenarios, con una instrucci\u00f3n clara: territorio, unidad y presencia permanente\u2026","rel":"","context":"En \u00abOPINI\u00d3N\u00bb","block_context":{"text":"OPINI\u00d3N","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/category\/columnistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/ALMA-3108.png?fit=1200%2C658&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/ALMA-3108.png?fit=1200%2C658&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/ALMA-3108.png?fit=1200%2C658&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/ALMA-3108.png?fit=1200%2C658&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/08\/ALMA-3108.png?fit=1200%2C658&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":87471,"url":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/08\/03\/las-elecciones-del-2027-seran-el-termometro-politico-y-social-de-la-presidenta-claudia-sheinbaum\/","url_meta":{"origin":20967,"position":5},"title":"Las elecciones del 2027 ser\u00e1n el term\u00f3metro pol\u00edtico y social de la presidenta Claudia Sheinbaum","author":"Redacci\u00f3n Pol\u00edticos","date":"3 de agosto de 2026","format":false,"excerpt":"LEAD POL\u00cdTICO\u2026 Por: Ren\u00e9 Mart\u00ednez Torres Los procesos electorales federales del 2027, la renovaci\u00f3n del Senado de la Rep\u00fablica, el Congreso Federal, 17 estados renovar\u00e1n sus gubernaturas, en algunas entidades solo habr\u00e1 elecci\u00f3n de diputados locales y federales como el caso de Veracruz, ser\u00e1 el term\u00f3metro pol\u00edtico y social de\u2026","rel":"","context":"En \u00abOPINI\u00d3N\u00bb","block_context":{"text":"OPINI\u00d3N","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/category\/columnistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/02\/LEAD-POLITICO-AZUL.jpg?fit=800%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/02\/LEAD-POLITICO-AZUL.jpg?fit=800%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/02\/LEAD-POLITICO-AZUL.jpg?fit=800%2C445&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/02\/LEAD-POLITICO-AZUL.jpg?fit=800%2C445&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/06\/P-SERGIO-GTZ-VERACRUZ-1.png?fit=1816%2C1016&ssl=1","_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/20967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=20967"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/20967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/20968"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=20967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=20967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=20967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}