{"id":24437,"date":"2023-10-06T09:22:59","date_gmt":"2023-10-06T14:22:59","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=24437"},"modified":"2023-10-06T09:22:59","modified_gmt":"2023-10-06T14:22:59","slug":"rusia-prueba-con-exito-misil-balistico","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/10\/06\/rusia-prueba-con-exito-misil-balistico\/","title":{"rendered":"Rusia prueba con \u00e9xito misil bal\u00edstico"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">RUSIA.- Vladimir Putin dijo el jueves que Rusia hab\u00eda probado con \u00e9xito un nuevo y potente misil estrat\u00e9gico y plante\u00f3 el jueves la posibilidad de que Mosc\u00fa pueda reanudar las pruebas nucleares por primera vez en m\u00e1s de tres d\u00e9cadas, as\u00ed como retirar su ratificaci\u00f3n de un hist\u00f3rico tratado de prohibici\u00f3n de pruebas nucleares.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Putin dijo por primera vez que Mosc\u00fa hab\u00eda probado con \u00e9xito el Burevestnik, un misil de crucero con capacidad y propulsi\u00f3n nuclear con un alcance potencial de muchos miles de millas. Tambi\u00e9n dijo en una reuni\u00f3n anual de analistas y periodistas que Rusia casi hab\u00eda completado el trabajo en su sistema de misiles bal\u00edsticos intercontinentales Sarmat, otro elemento clave de su nueva generaci\u00f3n de armas nucleares.<\/span><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24438\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/10\/A15c-1.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/10\/A15c-1.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/10\/A15c-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/10\/A15c-1.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><span style=\"font-size: 14pt;\">Putin, quien ha recordado repetidamente al mundo el poder nuclear de Rusia desde que lanz\u00f3 su invasi\u00f3n a Ucrania el 24 de febrero de 2022, dijo que nadie en su sano juicio usar\u00eda armas nucleares contra Rusia.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Rusia no ha realizado una prueba que implique una explosi\u00f3n nuclear desde 1990, el a\u00f1o antes del colapso de la Uni\u00f3n Sovi\u00e9tica, pero Putin se neg\u00f3 a descartar la posibilidad de que pudiera reanudar dichas pruebas. Se\u00f1al\u00f3 que Estados Unidos no hab\u00eda ratificado el tratado que proh\u00edbe los ensayos nucleares, mientras que Rusia lo hab\u00eda firmado y ratificado. En teor\u00eda, ser\u00eda posible que la Duma, el parlamento ruso, revocara su ratificaci\u00f3n, afirm\u00f3.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Los analistas militares dicen que una reanudaci\u00f3n de las pruebas nucleares por parte de Rusia, Estados Unidos o ambos ser\u00eda profundamente desestabilizadora en un momento en que las tensiones entre los dos pa\u00edses son mayores que en cualquier otro momento de los \u00faltimos 60 a\u00f1os. En febrero, Putin suspendi\u00f3 la participaci\u00f3n de Rusia en el nuevo tratado START que limita la cantidad de armas nucleares que cada parte puede desplegar.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Pero Putin dijo que no era necesario que Rusia reescribiera su doctrina sobre el uso real de armas nucleares, que dice que puede dispararlas ya sea en respuesta a un ataque nuclear contra ella o en caso de una amenaza a la existencia del estado.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Karaganov ha llamado la atenci\u00f3n entre los analistas estrat\u00e9gicos rusos y occidentales al argumentar que es hora de que Rusia reduzca su umbral de uso nuclear para \u00abcontener, asustar y calmar a nuestros oponentes\u00bb. Escribi\u00f3 en un art\u00edculo reciente que Rusia deber\u00eda \u00absacudir\u00bb a sus enemigos amenazando con ataques nucleares contra pa\u00edses europeos y bases estadounidenses en Europa.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUSIA.- Vladimir Putin dijo el jueves que Rusia hab\u00eda probado con \u00e9xito un nuevo y potente misil estrat\u00e9gico y plante\u00f3<\/p>\n","protected":false},"author":4,"featured_media":24439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[],"class_list":["post-24437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/10\/OIP.jpg?fit=474%2C314&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/24437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=24437"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/24437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/24439"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=24437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=24437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=24437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}