{"id":27703,"date":"2023-12-18T09:37:29","date_gmt":"2023-12-18T15:37:29","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=27703"},"modified":"2023-12-18T09:37:29","modified_gmt":"2023-12-18T15:37:29","slug":"chile-firme-rechazo-a-una-constitucion-de-la-ultraderecha","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2023\/12\/18\/chile-firme-rechazo-a-una-constitucion-de-la-ultraderecha\/","title":{"rendered":"Chile: firme rechazo a una Constituci\u00f3n de la ultraderecha"},"content":{"rendered":"<div class=\"col col1\">\n<p class=\"s-s\"><span style=\"font-size: 14pt;\">Santiago.- Los ciudadanos de Chile rechazaron ayer de manera contundente un proyecto de Constituci\u00f3n escrito sin contrapesos por el ultraconservador Partido Republicano, con el respaldo de la derecha tradicional, y que ahondaba la institucionalidad neoliberal vigente, un desenlace que en lo inmediato pone t\u00e9rmino al debate constitucional, tras el fracaso de dos procesos desde 2019.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Con 99.3 por ciento del escrutinio, el\u00a0<q>a favor<\/q>\u00a0obten\u00eda 44.24 por ciento de sufragios (5 millones 443 mil 201), mientras la opci\u00f3n\u00a0<q>en contra<\/q>\u00a0alcanzaba 55.76 por ciento (6 millones 860 mil 719), con una participaci\u00f3n de 81.4 por ciento. De las 15 regiones del pa\u00eds, s\u00f3lo en tres ganaba por m\u00ednima diferencia\u00a0<q>a favor<\/q>.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">La victoria del\u00a0<q>en contra<\/q>\u00a0pareci\u00f3 clara apenas iniciado el escrutinio, estableciendo una ventaja de ocho puntos que fue progresivamente ampli\u00e1ndose al punto que, una hora despu\u00e9s trascendi\u00f3 que el comando del\u00a0<q>a favor<\/q>, desmontaba el escenario callejero que hab\u00eda preparado para celebrar una hipot\u00e9tica victoria.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Para la centroizquierda, incluida la presidencia de Gabriel Boric, se trata de un b\u00e1lsamo y un alivio luego de la aplastante derrota que sufri\u00f3 en septiembre de 2022, cuando el proyecto radical escrito por las fuerzas progresistas entonces mayoritarias fue rechazado por 68 por ciento de los electores. Se trata tambi\u00e9n de un respiro ante el avance arrollador de la ultraderecha y, sobre todo, una oportunidad para que el gobierno de Boric retome cierta iniciativa pol\u00edtica.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Pero la\u00a0<q>victoria<\/q>\u00a0de ayer tiene tambi\u00e9n sabor a hiel para el progresismo, porque a final de cuentas, tras la revuelta social de 2019 que pareci\u00f3 cavar su tumba, permanecer\u00e1 vigente el texto escrito en 1980 durante la dictadura de Augusto Pinochet, institucionalizando el neoliberalismo, la privatizaci\u00f3n de los derechos sociales y en general la mercantilizaci\u00f3n de toda la vida ciudadana.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Parece una iron\u00eda feroz que tras una desgastadora experiencia de cuatro a\u00f1os iniciada en octubre de 2019, cuando millones salieron a las calles a exigir cambios, con varias decenas de muertos y centenares de heridos, todo vuelve al punto de partida: no hay reformas estructurales, no hay ampliaci\u00f3n de la democracia, no hay ajustes en los sistemas individualistas de pensiones y de salud, tampoco un alza de impuestos a la renta de los m\u00e1s ricos que se requiere para financiar aquellos.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">La victoria del\u00a0<q>en contra<\/q>\u00a0por su amplia diferencia, suponen un certero golpe a las pretensiones presidenciales de Jos\u00e9 Antonio Kast, el l\u00edder de los ultraconservadores republicanos, que fueron la fuerza pol\u00edtica mayoritaria en el Consejo Constitucional que redact\u00f3 la propuesta derrotada. Kast, confeso admirador de Pinochet, gan\u00f3 en diciembre de 2021 la primera vuelta presidencial a Boric y desde entonces ha seguido proyectando sus intenciones presidenciales.<\/span><\/p>\n<\/div>\n<div class=\"col col2\">\n<p><span style=\"font-size: 14pt;\"><q>Esta noche una gran mayor\u00eda de chilenos ha rechazado la propuesta constitucional que nosotros propusimos desde el Consejo Constitucional y reconocemos esa derrota con mucha claridad y tambi\u00e9n con mucha humildad<\/q>, dijo.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Agreg\u00f3 que\u00a0<q>no hay nada que celebrar, no s\u00f3lo nosotros no podemos celebrar, sino que el gobierno y la izquierda tampoco pueden hacerlo, porque el da\u00f1o que ha sufrido Chile en los \u00faltimos cuatro a\u00f1os es gigantesco y costar\u00e1 muchas d\u00e9cadas repararlo<\/q>, a\u00f1adi\u00f3.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El l\u00edder republicano asegur\u00f3 que\u00a0<q>hoy los chilenos han dicho de manera clara que prefieren continuar con la Constituci\u00f3n actual, cerrando esta larga discusi\u00f3n. Esta voluntad de los chilenos nos permitir\u00e1 terminar con la incertidumbre y comenzar a recuperar la esperanza, el orden, la paz y el progreso que hemos perdido<\/q>.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Pasadas las 9 de la noche (hora local), el presidente Boric pronunci\u00f3 un discurso en televisi\u00f3n en el cual se\u00f1al\u00f3: \u201cdurante nuestro mandato se cierra el tema constitucional, (porque) las urgencias son otras.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><q>Nuestro pa\u00eds seguir\u00e1 con la Constituci\u00f3n vigente porque luego de dos propuestas constitucionales plebiscitadas, ninguna logr\u00f3 representar y unir a Chile en su diversidad. El pa\u00eds se polariz\u00f3, se dividi\u00f3 y, al margen de este contundente resultado, el proceso constitucional no logr\u00f3 canalizar las esperanzas de tener una nueva Constituci\u00f3n redactada para todos<\/q>, reconoci\u00f3.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santiago.- Los ciudadanos de Chile rechazaron ayer de manera contundente un proyecto de Constituci\u00f3n escrito sin contrapesos por el ultraconservador<\/p>\n","protected":false},"author":4,"featured_media":27704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[],"class_list":["post-27703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/12\/chile.jpg?fit=1024%2C682&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/27703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=27703"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/27703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/27704"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=27703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=27703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=27703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}