{"id":34345,"date":"2024-04-02T10:23:11","date_gmt":"2024-04-02T16:23:11","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=34345"},"modified":"2024-04-02T10:23:11","modified_gmt":"2024-04-02T16:23:11","slug":"el-beneficio-de-aplicar-la-ley","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2024\/04\/02\/el-beneficio-de-aplicar-la-ley\/","title":{"rendered":"El beneficio de aplicar la ley"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\"><strong>Por Alberto Woolrich Ort\u00edz<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Muy en los principios de la historia jur\u00eddica exist\u00eda y se hac\u00eda valer la ley del m\u00e1s fuerte, al nacer las hordas, clanes, tribus y sectas se dio origen a seleccionar a alguien para ejercer el mando. Por aquellos siglos exist\u00eda la venganza privada, conocida por los juristas de hoy como la aplicaci\u00f3n de la ley del tali\u00f3n \u201cojo por ojo y diente por diente\u201d, la justicia en aquellos tiempos \u2013como ahora en algunas regiones del Pa\u00eds-, se hac\u00eda por propia mano de quien se estimaba v\u00edctima de abusos seg\u00fan el caso concreto.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Tiempo despu\u00e9s cuando se organiz\u00f3 el poder social, \u00e9ste se encargaba de ejercer justicia, ya fuera en nombre de alguna deidad o del inter\u00e9s de las c\u00e9lulas, castas, linajes o cuadrillas para tener una salvaguarda y contener con ello la inseguridad, el desorden y la intranquilidad.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Por aquellos siglos nacieron los recintos de justicia y las leyes para distinguir quienes eran v\u00edctimas de hechos infamantes y delictivos, a los cuales se les conduc\u00eda ante aquellos recintos de justicia, encargados de decidir, sancionar e impartirla.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Muchos de aquellos hist\u00f3ricos recintos de justicia se malograron y decepcionaron, resultaron por ende un fiasco, debido a que las acciones populares fracasaron, ya que los gobernados hicieron ver que era indispensable contar con un medio para defenderse de los oprobios. Ese medio fue el primer cimiento para crear instituciones del ministerio p\u00fablico en la Roma antigua; ah\u00ed fue el g\u00e9nesis de una alta conciencia del valor del derecho.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Algunos viejos togados estiman que el procedimiento indagador fue el arranque de \u00e9ste paso decisivo en la historia del procedimiento penal y la \u2014persecuci\u00f3n de los delitos&#8211;. Ojal\u00e1 esto lo pudiera apreciar la Fiscal\u00eda General de la Rep\u00fablica de la Cuarta Transformaci\u00f3n de la Naci\u00f3n, por ser ello una misi\u00f3n del Estado.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">La Academia de Derecho Penal del Colegio Nacional de Abogados Foro de M\u00e9xico, al introducirse a la historia y evoluci\u00f3n que ha sufrido la representaci\u00f3n social, sabe que remontarse a su origen, al desarrollo y la transformaci\u00f3n de \u00e9sta se mantiene lo que se conoce como un Estado de Derecho. Su estudio y aplicaci\u00f3n en \u00e9sta \u00e9poca pol\u00edtica resulta de vital importancia, porque permitir\u00eda al Poder Ejecutivo del hoy o del ma\u00f1ana conocer el pasado; les explicar\u00eda la importancia de combatir a la narco delincuencia pol\u00edtica y la corrupci\u00f3n como consecuencia de sucesos acontecidos en el neoliberalismo y, con ello ofertar\u00eda a los presentes o futuros gobernantes valiosos ejemplos y fecundas ense\u00f1anzas que les permitir\u00edan considerar un futuro promisorio para M\u00e9xico, libre de la corrupci\u00f3n y narco-pol\u00edtica, con el s\u00f3lo beneficio que conllevar\u00eda el aplicar la ley.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Es cu\u00e1nto.<\/span><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34199\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2024\/04\/FIRMA-EDITORIAL-PD.jpg?resize=800%2C98&#038;ssl=1\" alt=\"\" width=\"800\" height=\"98\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2024\/04\/FIRMA-EDITORIAL-PD.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2024\/04\/FIRMA-EDITORIAL-PD.jpg?resize=300%2C37&amp;ssl=1 300w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2024\/04\/FIRMA-EDITORIAL-PD.jpg?resize=768%2C94&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Alberto Woolrich Ort\u00edz Muy en los principios de la historia jur\u00eddica exist\u00eda y se hac\u00eda valer la ley del<\/p>\n","protected":false},"author":4,"featured_media":3845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":["post-34345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/CABEZAL-ALBERTO-WOOD.png?fit=1816%2C1016&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/34345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=34345"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/34345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3845"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=34345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=34345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=34345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}