{"id":36146,"date":"2024-04-29T03:53:01","date_gmt":"2024-04-29T08:53:01","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=36146"},"modified":"2024-04-29T03:53:01","modified_gmt":"2024-04-29T08:53:01","slug":"se-investigaran-fallas-de-internet-para-medios-en-segundo-debate-ine","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2024\/04\/29\/se-investigaran-fallas-de-internet-para-medios-en-segundo-debate-ine\/","title":{"rendered":"Se investigar\u00e1n fallas de internet para medios en segundo debate: INE"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">El INE dijo que investigar\u00e1 las fallas en el internet ocurridas durante el debate presidencial, mismas que afectaron a la sala de prensa instalada en un extremo de los Estudios Churubusco.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En un comunicado difundido a la una de la ma\u00f1ana, tres horas despu\u00e9s del t\u00e9rmino del debate, ofrece disculpas por lo ocurrido, y puntualiz\u00f3 que el internet \u201cfue brindado por una empresa proveedora\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Dijo que se detect\u00f3 esta situaci\u00f3n, personal de la Coordinaci\u00f3n Nacional de Comunicaci\u00f3n Social (CNCS), en colaboraci\u00f3n con la Unidad T\u00e9cnica de Servicios de Inform\u00e1tica (UTSI), solicit\u00f3 a la empresa que atendiera las causas de la falla a fin de restablecer de inmediato el servicio.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cPosterior a esto, el INE verific\u00f3 que se restaurara el servicio de internet, el cual estuvo disponible para los medios de comunicaci\u00f3n en el resto de la transmisi\u00f3n del debate. \u201cDebido a que se dieron intermitencias en el servicio durante el transcurso del debate, el INE inici\u00f3 las investigaciones de manera inmediata con el objetivo de deslindar responsabilidades y tomar las acciones pertinentes\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Indic\u00f3 que el seguimiento puntual de estos incidentes se dar\u00e1 en el seno de la Comisi\u00f3n Temporal de Debates del Instituto.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cEl INE lamenta cualquier inconveniente ocasionado por las intermitencias en el servicio de internet durante el debate. Agradecemos la comprensi\u00f3n de los medios de comunicaci\u00f3n y el p\u00fablico. Cabe destacar que se est\u00e1 investigando el incidente para tomar las medidas pertinentes y evitar futuras eventualidades\u201d, agreg\u00f3.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El INE dijo que investigar\u00e1 las fallas en el internet ocurridas durante el debate presidencial, mismas que afectaron a la<\/p>\n","protected":false},"author":4,"featured_media":36147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[33],"tags":[1378,3185,43,593],"class_list":["post-36146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-debate","tag-fallas","tag-ine","tag-internet"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2024\/04\/111440393_1.jpg?fit=640%2C360&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/36146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=36146"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/36146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/36147"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=36146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=36146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=36146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}