{"id":37776,"date":"2024-05-17T11:42:46","date_gmt":"2024-05-17T16:42:46","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=37776"},"modified":"2024-05-17T11:42:46","modified_gmt":"2024-05-17T16:42:46","slug":"la-cruda-realidad-de-veracruz-contra-la-ficcion-morenista","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2024\/05\/17\/la-cruda-realidad-de-veracruz-contra-la-ficcion-morenista\/","title":{"rendered":"La cruda realidad de Veracruz contra la ficci\u00f3n morenista"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\"><strong>Por Aurelio Contreras Moreno<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Con poca resonancia medi\u00e1tica, pero con una trascendencia m\u00e1s que relevante, transcurri\u00f3 la presentaci\u00f3n de los \u201cCompromisos por la Paz\u201d que se llev\u00f3 a cabo esta semana en Xalapa, y que forma parte del Di\u00e1logo Nacional por la Paz para buscar frenar la violencia en el pa\u00eds.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El objetivo planteado en el encuentro celebrado el martes pasado fue \u201cgenerar un espacio de di\u00e1logo plural e incluyente para articular iniciativas locales y construir una agenda estatal de paz que atienda la realidad de inseguridad y violencia que impera en Veracruz\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El Di\u00e1logo Nacional concluy\u00f3 con un \u201cAcuerdo Ciudadano por la Paz\u201d para \u201cimpulsar la implementaci\u00f3n de la Agenda Nacional de Paz en los diferentes sectores de la sociedad, presentarla a todos los candidatos y candidatas a un puesto de elecci\u00f3n, y crear una Red Nacional por la Paz para articular procesos locales, estatales y nacionales\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En Xalapa se convoc\u00f3 a colectivos de derechos humanos, organismos no gubernamentales, representantes de la Iglesia Cat\u00f3lica \u2013promotora del Di\u00e1logo Nacional por la Paz, a ra\u00edz del asesinato de dos sacerdotes jesuitas a manos de narcotraficantes en Chihuahua en junio de 2022-, activistas y, fundamentalmente a las candidaturas a la gubernatura de Veracruz, pues finalmente quien gobierne la entidad a partir del 1 de diciembre de 2024, ser\u00e1 quien asuma la responsabilidad de aplicar -o no- lo que se concluy\u00f3 respecto de la situaci\u00f3n por la que atraviesa Veracruz y que abarca no solo la seguridad, sino el respeto a la democracia y las libertades.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El documento \u201cCompromisos por la Paz\u201d contiene un crudo diagn\u00f3stico sobre el Veracruz de a de veras. Por ejemplo, en materia de Justicia, sentencia que el \u00edndice de impunidad es de 94.1 por ciento y \u201cnos mantiene como uno de los estados m\u00e1s rezagados en materia de acceso a la justicia\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cEn algunas regiones, especialmente en el sur del Veracruz, la Fiscal\u00eda General del Estado fabrica culpables, usurpando la personalidad de los ciudadanos, alterando las pruebas o los testimonios para iniciar carpetas de investigaci\u00f3n por consigna\u201d, se\u00f1ala.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El diagn\u00f3stico sostiene que Veracruz \u201choy padece un retroceso en materia de democracia que se encamina a romper con la estructura constitucional construida en los \u00faltimos a\u00f1os. Las autoridades gubernamentales son recurrentes a la exclusi\u00f3n de los reclamos ciudadanos. Pero tambi\u00e9n se distinguen por el desorden en la administraci\u00f3n p\u00fablica y en la ausencia de transparencia y rendici\u00f3n de cuentas. Es constante la improvisaci\u00f3n en la aplicaci\u00f3n de pol\u00edticas p\u00fablicas. Adem\u00e1s, se ha permitido que la violencia y la extorsi\u00f3n ocasionada por la delincuencia organizada mantengan sometidos a amplios n\u00facleos de la poblaci\u00f3n en algunas regiones de nuestra entidad\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En lo relativo al indicador de las condiciones para el ejercicio de una prensa libre, \u00e9sta es agredida constantemente. Art\u00edculo 19 ha registrado en los \u00faltimos a\u00f1os 33 asesinatos de periodistas y se tienen registradas ocho desapariciones, menciona el documento.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En materia de derechos humanos, el diagn\u00f3stico de los \u201cCompromisos por la Paz\u201d asegura que en el estado de Veracruz \u201cse vive un deterioro en el respeto pleno a los mismos, lo que ha derivado en mayor discriminaci\u00f3n que se acent\u00faa en los grupos que viven en una situaci\u00f3n de mayor vulnerabilidad\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cEsta realidad se hace especialmente visible entre los grupos hist\u00f3ricamente discriminados, entre los que est\u00e1n las personas adultas mayores, (\u2026); las personas con discapacidad, respecto de las cuales hay nulas o escasas pol\u00edticas p\u00fablicas; las personas ind\u00edgenas de las que en el estado de Veracruz el 8.6 por ciento de la poblaci\u00f3n es hablante de una lengua ind\u00edgena, cifra que decreci\u00f3 en 0.7 por ciento (48 mil 59 personas) respecto de la d\u00e9cada anterior.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cNi\u00f1as, ni\u00f1os y adolescentes enfrentan como uno de sus mayores riesgos la violencia, acoso escolar y maltrato infantil en los entornos escolares, problem\u00e1tica que pese a tener un cuerpo normativo vigente con protocolos de atenci\u00f3n desde hace m\u00e1s de diez a\u00f1os, no se cumplen a cabalidad; respecto de la violencia sexual y digital a lo que hay que a\u00f1adir que la violencia contra las ni\u00f1as y los ni\u00f1os incluye la violencia f\u00edsica, sexual y emocional, as\u00ed como el abandono y la exposici\u00f3n laboral\u201d, destaca una parte del documento.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Sobre la situaci\u00f3n que enfrentan las mujeres en Veracruz, el diagn\u00f3stico puntualiza que la falta de acceso a la justicia \u201ces la m\u00e1s importante deuda que el Estado mexicano en general y el de Veracruz en particular tienen con esta poblaci\u00f3n, tanto por la falta de mayor presupuesto destinado a la Fiscal\u00eda, como por la carencia de perspectiva de g\u00e9nero en la impartici\u00f3n de justicia, situaci\u00f3n que influye para que los niveles de impunidad en los casos de violencias denunciadas sigan siendo altos, especialmente en los casos de feminicidios, que siguen manteniendo a la entidad en los primeros lugares a nivel nacional\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Otra problem\u00e1tica espec\u00edfica es la que viven las mujeres y madres buscadoras de hijos e hijas desaparecidos, quienes \u201cno cuentan con los 46 recursos necesarios para realizar el trabajo de campo consistente en la b\u00fasqueda, exhumaci\u00f3n de fosas clandestinas, elaboraci\u00f3n de informes de hallazgos, etc\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Para establecer estrategias de pol\u00edticas p\u00fablicas ante esta radiograf\u00eda del horror, se invit\u00f3, como se indic\u00f3 ya, a la candidata y los candidatos a la gubernatura. Aunque ninguno pudo estar presente por encontrarse en medio de sus respectivas campa\u00f1as proselitistas, enviaron representantes -destacando la participaci\u00f3n de la senadora Beatriz Paredes- e incluso en video, se adhirieron a los \u201cCompromisos por la Paz\u201d. Salvo una.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En voz de su representante, la candidata a senadora Claudia Tello, la abanderada morenista a la gubernatura, Roc\u00edo Nahle, rechaz\u00f3 la realidad que los veracruzanos padecen todos los d\u00edas y casi casi firm\u00f3 bajo protesta los compromisos.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cSe presenta un escenario desalentador, grave, que se vivi\u00f3, s\u00ed, a\u00f1os atr\u00e1s, pero que hoy se ha ido superando. Que falta por hacer, claro, estamos en el camino (\u2026). El cambio de r\u00e9gimen del 2018 a la fecha ha mejorado las relaciones entre los que menos tienen y ha permitido avanzar en la justicia social\u201d, dijo Claudia Tello, que en sus seis a\u00f1os como diputada federal por Xalapa no gestion\u00f3 absolutamente nada por su distrito y sus representados.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Para la aspirante a senadora \u2013y por ende, para la que busca la gubernatura-, \u201cen Veracruz vivimos en el pasado tiempos con mucha violencia y miedo. Hoy las cosas han cambiado y aseguro estar\u00e1n mejor\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El activista por los derechos humanos de la zona de las Altas Monta\u00f1as, Jairo Guarneros \u2013presente en el encuentro-, public\u00f3 al respecto en sus redes sociales: \u201ccuando todos exponen la tragedia en la que se ha convertido el estado y la representante de do\u00f1a Nahle que se le ve\u00eda muy atenta a dichas exposiciones, sale conque hoy estamos muy bien, entonces queda claro que ya no tienen remedio\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u00bfEn qu\u00e9 dimensi\u00f3n viven esas candidatas de Morena, o de qu\u00e9 tama\u00f1o es su cinismo, como para intentar agarrar de pendeja a la gente de esa manera?<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Aurelio Contreras Moreno Con poca resonancia medi\u00e1tica, pero con una trascendencia m\u00e1s que relevante, transcurri\u00f3 la presentaci\u00f3n de los<\/p>\n","protected":false},"author":4,"featured_media":4397,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26],"tags":[],"class_list":["post-37776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/AURELIO-CONTRERAS-MORENO-1.png?fit=1816%2C1016&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/37776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=37776"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/37776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/4397"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=37776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=37776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=37776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}