{"id":38237,"date":"2024-05-24T07:39:32","date_gmt":"2024-05-24T12:39:32","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=38237"},"modified":"2024-05-24T07:39:32","modified_gmt":"2024-05-24T12:39:32","slug":"expertos-en-navegacion-advirtieron-peligro-de-choques-con-puente-de-baltimore","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2024\/05\/24\/expertos-en-navegacion-advirtieron-peligro-de-choques-con-puente-de-baltimore\/","title":{"rendered":"Expertos en navegaci\u00f3n advirtieron peligro de choques con puente de Baltimore"},"content":{"rendered":"<div class=\"content-body clearfix \">\n<div id=\"content-body-225-11968494\">\n<p><span style=\"font-size: 14pt;\">Expertos en navegaci\u00f3n\u00a0de\u00a0Maryland\u00a0advirtieron durante una d\u00e9cada sobre los\u00a0peligros de accidente de buques\u00a0con el\u00a0puente Francis Scott Key, que colaps\u00f3 en marzo tras el\u00a0choque de un portacontenedores, seg\u00fan inform\u00f3 este jueves el diario The Washington Post.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En marzo el\u00a0buque\u00a0carguero\u00a0Dali, de casi\u00a0300 metros de eslora\u00a0y con bandera de Singapur, choc\u00f3 cuando sal\u00eda del\u00a0Puerto de Baltimore\u00a0con uno de los pilares centrales del puente causando su colapso y la muerte de seis trabajadores que trabajaban en plena madrugada en reparaciones.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Durante casi una d\u00e9cada y a medida que\u00a0buques de carga\u00a0cada vez m\u00e1s grandes usaban el puerto de\u00a0Baltimore, un grupo denominado\u00a0Comit\u00e9 de Seguridad y Coordinaci\u00f3n Portuaria analiz\u00f3 los puentes Key y el que cruza la Bah\u00eda de Chesapeake, entre otros.<\/span><\/p>\n<article class=\"mundo\nmedia col-md-4 inline-story \"><\/p>\n<div class=\"teaser \">\n<div class=\"img-container picture\"><\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<article class=\"content-continued-body clearfix \">\n<div id=\"content-body-5851641-11968494\">\n<p><span style=\"font-size: 14pt;\">\u00abLos timoneles de Maryland, especialistas que abordan las naves mayores y las gu\u00edan al arribo y cuando zarpan del puerto &#8211; dieron alarmas en particular acerca de que los puentes locales necesitaban m\u00e1s protecci\u00f3n de buques desviados, seg\u00fan muestran los documentos\u00bb, afirm\u00f3 el diario.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u00abLos documentos no incluyen indicios de que lo discutido por el comit\u00e9 de seguridad haya resultado en nuevas protecciones f\u00edsicas para el puente Key\u00bb, agreg\u00f3.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Las minutas de las reuniones de ese comit\u00e9 \u00abcircularon entre las agencias representadas en el grupo, seg\u00fan Frank Hamons, quien ayud\u00f3 a establecer el comit\u00e9 cuando era gerente de dragado de la Administraci\u00f3n Portuaria de Maryland, en los a\u00f1os 1980, y la presidi\u00f3 hasta 2013\u00bb, seg\u00fan el Post.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Pero, agreg\u00f3 el diario, \u00abno est\u00e1 claro qui\u00e9n dentro de las agencias vio realmente esas minutas, y numerosos exfuncionarios de alta jerarqu\u00eda en el tr\u00e1nsito de Maryland dijeron al Post que no recordaban siquiera haber sido informados de las discusiones sobre la protecci\u00f3n de los puentes\u00bb.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Las autoridades federales siguen investigando la\u00a0causas del accidente del Dali.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El lunes pasado, el\u00a0Dali\u00a0fue remolcado en una traves\u00eda de cuatro kil\u00f3metros hasta la\u00a0Terminal Marina Seagirt\u00a0desde el sitio donde el\u00a0choque\u00a0caus\u00f3 el\u00a0colapso del puente\u00a0y donde hab\u00eda estado atrapado bajo la\u00a0estructura\u00a0demolida.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El\u00a0colapso del puente, que afect\u00f3 uno de los trayectos de la Autopista Interestatal 95 y el tr\u00e1nsito entre\u00a0Washington DC y Nueva York, caus\u00f3 la\u00a0muerte de seis trabajadores,\u00a0inmigrantes\u00a0de Centroam\u00e9rica y M\u00e9xico, que hac\u00edan\u00a0reparaciones\u00a0en la carretera\u00a0durante la noche.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Un informe de la\u00a0Junta de Seguridad de Transporte Nacional\u00a0(NTSB, por sus siglas en ingl\u00e9s) indic\u00f3 que el d\u00eda previo al accidente, Dali perdi\u00f3 energ\u00eda el\u00e9ctrica en dos ocasiones mientras se hallaba atracado en el Puerto de Baltimore.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Por su parte, el Bur\u00f3 Federal de Investigaciones (FBI) abri\u00f3 una investigaci\u00f3n criminal, mientras que el Gobierno de la ciudad de Baltimore demand\u00f3 a la compa\u00f1\u00eda propietaria, Grace Ocean Private Limited, y a la administradora, Synergy Marine PTE LTD, ambas de Singapur, por este accidente que ha causado p\u00e9rdidas millonarias.<\/span><\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Expertos en navegaci\u00f3n\u00a0de\u00a0Maryland\u00a0advirtieron durante una d\u00e9cada sobre los\u00a0peligros de accidente de buques\u00a0con el\u00a0puente Francis Scott Key, que colaps\u00f3 en marzo<\/p>\n","protected":false},"author":4,"featured_media":38238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[3486],"class_list":["post-38237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-puente-baltimore"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2024\/05\/4YV7LG6LJJAQNMZKPNUILDCMEU.jpg?fit=1920%2C1281&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/38237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=38237"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/38237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/38238"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=38237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=38237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=38237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}