{"id":4120,"date":"2022-04-19T22:17:03","date_gmt":"2022-04-20T03:17:03","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=4120"},"modified":"2022-04-19T22:17:03","modified_gmt":"2022-04-20T03:17:03","slug":"petro-denuncia-campana-de-asedio-de-la-derecha","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2022\/04\/19\/petro-denuncia-campana-de-asedio-de-la-derecha\/","title":{"rendered":"Petro denuncia campa\u00f1a de asedio de la derecha"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p class=\"p1\"><em><strong>Bogot\u00e1.<\/strong><\/em> <strong>Gustavo Petro<\/strong>, <strong>candidato del partido Colombia Humana a siete semanas de las elecciones presidenciales en Colombia, denunci\u00f3 una campa\u00f1a de difamaci\u00f3n contra el Pacto Hist\u00f3rico para descarrilar su candidatura que va a la cabeza.<\/strong><\/p>\n<p class=\"p1\">La campa\u00f1a medi\u00e1tica publica una fotograf\u00eda de Juan Fernando Petro, hermano del candidato, entrando a la c\u00e1rcel de la Picota el pasado 8 de abril, y un documento ap\u00f3crifo que circul\u00f3 dentro del penal sobre una supuesta rebaja de penas para beneficiar a pol\u00edticos y criminales presos.<\/p>\n<p class=\"p1\">La visita al penal de Juan Fernando Petro tuvo como motivo hablar con algunos reclusos sobre el tema de los derechos humanos y de otras cuestiones humanitarias en las prisiones y no hubo ning\u00fan ofrecimiento al respecto, seg\u00fan la declaraci\u00f3n de los testigos presentes en la reuni\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4122 size-large\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/P-PETRO2-1024x573.png?resize=800%2C448&#038;ssl=1\" alt=\"\" width=\"800\" height=\"448\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/P-PETRO2.png?resize=1024%2C573&amp;ssl=1 1024w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/P-PETRO2.png?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/P-PETRO2.png?resize=768%2C430&amp;ssl=1 768w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/P-PETRO2.png?resize=1536%2C859&amp;ssl=1 1536w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/P-PETRO2.png?w=1816&amp;ssl=1 1816w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/P-PETRO2.png?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\">Seg\u00fan el candidato del Pacto Hist\u00f3rico <strong>\u00abhoy podemos decir que un sector de la prensa y un candidato presidencial mintieron y nos calumniaron\u201d.<\/strong><\/p>\n<blockquote>\n<p class=\"p1\">Jam\u00e1s hubo un ofrecimiento de rebajas de penas por votos ni lo habr\u00e1\u00bb, agreg\u00f3 el candidato en su cuenta de Twitter de cara a las elecciones presidenciales del 29 de mayo.<\/p>\n<p class=\"p1\">El candidato de Equipo por Colombia, Federico Guti\u00e9rrez, acus\u00f3 a Gustavo Petro de estar buscando \u201cvotos a cambio de rebajas de penas\u201d.<\/p>\n<\/blockquote>\n<p class=\"p1\">Por su parte, el <strong>Pacto Hist\u00f3rico asegur\u00f3 que no tiene planeado ninguna reforma a la justicia en caso de llegar a la Presidencia, ni que est\u00e9 considerando rebajas de penas a pol\u00edticos y criminales, como lo aseguraran los partidos de derecha.\u00a0<\/strong><\/p>\n<p class=\"p1\">Por otra parte, para disuadir a sus cr\u00edticos de la derecha, el candidato izquierdista y el favorito en las encuestas, Gustavo Petro, se comprometi\u00f3 ante un notario a no realizar expropiaciones si llega a la presidencia de Colombia.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Bogot\u00e1. Gustavo Petro, candidato del partido Colombia Humana a siete semanas de las elecciones presidenciales en Colombia, denunci\u00f3 una<\/p>\n","protected":false},"author":4,"featured_media":4121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[463,462],"class_list":["post-4120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-colombia-humana","tag-gustavo-petro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/04\/P-PETRO1.png?fit=1816%2C1016&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4120"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/4121"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}