{"id":44403,"date":"2024-08-19T07:57:32","date_gmt":"2024-08-19T12:57:32","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=44403"},"modified":"2024-08-19T07:57:32","modified_gmt":"2024-08-19T12:57:32","slug":"los-mensajes-del-ultimo-informe-de-cuitlahuac","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2024\/08\/19\/los-mensajes-del-ultimo-informe-de-cuitlahuac\/","title":{"rendered":"Los mensajes del \u00faltimo informe de Cuitl\u00e1huac"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">Por: Luis Ram\u00edrez Baqueiro<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\"><em>\u201cEl liderazgo es una oportunidad de servir; no de lucirse.\u201d \u2013 J. Donald Walters.<\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Se lleg\u00f3 la fecha, 18 de agosto de 2024. La cuenta regresiva para la conclusi\u00f3n de la administraci\u00f3n estatal de Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez est\u00e1 en marcha.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Lo previamente acordado con la presidenta electa Claudia Sheinbaum sigue en pie, a pesar del tiro en el tim\u00f3n y no haberlo designado titular de la Comisi\u00f3n Federal de Electricidad (CFE), a donde ya le hab\u00edan prometido.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Las razones de ese cambio solo Claudia Sheinbaum las conoce, lo cierto es que ya confirm\u00f3 p\u00fablicamente que lo incorporar\u00e1 a su Gobierno, la dependencia ser\u00e1 lo de menos, lo que realmente importa es que el reloj sigue corriendo, y los tiempos de su administraci\u00f3n no empatan con los de la futura presidenta de M\u00e9xico.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Eso deja abierta la puerta para la que ser\u00e1 su salida, una solicitud de licencia anticipada para incorporarse al Gobierno Federal y dejar\u00e1 a Veracruz y los veracruzanos en manos de alguien m\u00e1s.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Todo eso ya se tiene listo y preparado, el movimiento est\u00e1 previamente autorizado por la actual gobernadora electa Roc\u00edo Nahle Garc\u00eda y el movimiento de transici\u00f3n asegura ser terso y delicado.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El personaje que arribar\u00e1 a la titularidad del Ejecutivo cuenta con la ven\u00eda de la presidenta electa, de la gobernadora electa y si no bastaba ello del presidente en funciones Andr\u00e9s Manuel L\u00f3pez Obrador.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El movimiento ser\u00e1 muy b\u00e1sico y sencillo, est\u00e1 marcado por la propia constituci\u00f3n de Veracruz, y ser\u00e1 el Congreso el encargado de llamar al personaje.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Pero retornando al evento que da paso al arranque del conteo regresivo en la historia pol\u00edtica de Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez, es de llamar la atenci\u00f3n algunos datos y hechos que ah\u00ed mismo se presentaron.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El Auditorio Benito Ju\u00e1rez volvi\u00f3 a lucir majestuoso como en los tiempos del otrora poderoso priismo veracruzano en la d\u00e9cada de los 70\u2019s y 80\u2019s del siglo XX, en el que los Gobernadores ocuparon ese recinto como el m\u00e1s suntuoso para hacer sus eventos, siempre bajo la custodia del DIF Estatal.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">As\u00ed por principio de cuentas Cuitl\u00e1huac Garc\u00eda asegur\u00f3 que su administraci\u00f3n impuso el r\u00e9cord de obras en un sexenio al ejecutar mil 046 obras divididas en 528 de carreteras, 502 urbanas y 16 de telecomunicaciones por un monto de 14 mil 275 millones; a la fecha suman 2 mil 170 kil\u00f3metros de la red carretera estatal rehabilitados y 654 calles pavimentadas.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Ciertamente falt\u00f3 mucho por hacer en el tema carretero, pues las m\u00e1s importantes y visibles de estas carreteras lucen en deplorables condiciones, la m\u00e1s emblem\u00e1tica la Xalapa-Veracruz, que en los tramos no concesionados est\u00e1 para mentar madres, tan solo por citar algunas.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Hablo de inversi\u00f3n y ah\u00ed afirm\u00f3 que resalta el monto de 179 mil 448 millones de pesos (mdp) en inversi\u00f3n privada, 90 mil de \u00e9stos de procedencia extranjera y el proyecto Puerta al Sureste como el m\u00e1s importante de todos los tiempos, sin dejar atr\u00e1s a las micro, peque\u00f1as y medianas empresas y teniendo el sexenio de mayores exportaciones, con 690 mil mdp, a la par de consolidar los Polos de Desarrollo en el Corredor Interoce\u00e1nico del Istmo.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Mencion\u00f3 que, en el rubro de salud, su gobierno hace historia mediante la ejecuci\u00f3n de 4 mil 414 millones de pesos en acciones de infraestructura y equipamiento; en el que cabe mencionar la reconstrucci\u00f3n de 57 centros de salud, 546 mantenimientos y remodelaciones, cuatro nuevos hospitales y 54 intervenciones desde cero.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Dentro de la danza de cifras, una que es relevante mencionar es la que tiene que ver con el manejo financiero de Veracruz.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Garc\u00eda Jim\u00e9nez asegur\u00f3 que en ese \u00faltimo rubro se destaca la disminuci\u00f3n de la deuda estatal en 25 por ciento y el incremento de los ingresos en 107%, mientras la inversi\u00f3n p\u00fablica lleg\u00f3 a 43 mil 453 millones de pesos, sin adquirir pr\u00e9stamos de corto plazo y dejando 10 mil mdp a la siguiente administraci\u00f3n; un legado de orden, transparencia, disciplina y combate a la corrupci\u00f3n que permiti\u00f3 mejores calificaciones crediticias.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">De ser as\u00ed, ser\u00e1 la primera vez desde el Gobierno de Patricio Chirinos Calero que la administraci\u00f3n estatal permita transitar sin contratiempos financieros el paso a la siguiente responsable del manejo gubernamental estatal.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Llam\u00f3 la atenci\u00f3n las salutaciones con la mano alzada que intercambiar\u00e1 con el presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica, Juan Javier G\u00f3mez Cazar\u00edn, una forma por dem\u00e1s simb\u00f3lica en ese juego de mensajes que ahora imponen los tiempos transformadores de Morena.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Aun cuando la gobernadora electa Roc\u00edo Nahle Garc\u00eda no estuvo presente por que atiende asuntos de orden personal fuera de la entidad, todo su futuro gabinete estuvo presente encabezados por el alcalde de Xalapa, Don Ricardo Ahued Bardahuil, quien ser\u00e1 el responsable de mantener el orden y la gobernabilidad del nuevo gobierno.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u00a1Cuitl\u00e1huac Garc\u00eda se va\u2026 y la cuenta regresiva ha comenzado!<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Al tiempo.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Luis Ram\u00edrez Baqueiro &nbsp; \u201cEl liderazgo es una oportunidad de servir; no de lucirse.\u201d \u2013 J. Donald Walters. \u00a0<\/p>\n","protected":false},"author":4,"featured_media":38306,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":["post-44403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2024\/05\/ASTROLABIO-4.jpg?fit=1816%2C1016&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/44403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=44403"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/44403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/38306"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=44403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=44403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=44403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}