{"id":46007,"date":"2024-09-10T20:16:46","date_gmt":"2024-09-11T01:16:46","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=46007"},"modified":"2024-09-10T20:16:46","modified_gmt":"2024-09-11T01:16:46","slug":"mas-escuelas-de-tuxpan-y-la-region-ya-cuentan-con-escrituras-lo-que-les-da-certeza-juridica","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2024\/09\/10\/mas-escuelas-de-tuxpan-y-la-region-ya-cuentan-con-escrituras-lo-que-les-da-certeza-juridica\/","title":{"rendered":"M\u00e1s escuelas de Tuxpan y la regi\u00f3n ya cuentan con escrituras, lo que les da certeza jur\u00eddica"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\"><em><strong>\u2022 El alcalde Jos\u00e9 Manuel Pozos asegur\u00f3 que las escuelas son s\u00edmbolo de esperanza, progreso y transformaci\u00f3n social.<\/strong><\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En el marco de la entrega de t\u00edtulos de propiedad del programa \u201cEscuela Garantizada, Escritura Garante\u201d, el Presidente Municipal Lic. Jos\u00e9 Manuel Pozos Castro destac\u00f3 que las escuelas son el n\u00facleo central de la educaci\u00f3n, porque en ellas se imparte el conocimiento y se impulsa el desarrollo humano integral.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Tuxpan fungi\u00f3 como sede para la entrega de escrituras a 33 planteles educativos de diversos niveles, de los municipios de \u00c1lamo Temapache, Castillo de Teayo, Chinampa de Gorostiza, Chumatl\u00e1n, Coatzintla, Nautla, Naranjos, Papantla, Tamal\u00edn, Tamiahua y Tuxpan, como parte del programa \u201cEscuela Garantizada, Escritura Garante\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En el mismo evento, se entregaron reconocimientos a nueve notarios p\u00fablicos que han contribuido con su trabajo a este programa, en beneficio de la comunidad estudiantil del estado.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Encabezaron la entrega el Mtro. V\u00edctor Emmanuel Vargas Barrientos, secretario de Educaci\u00f3n del estado de Veracruz; el alcalde Jos\u00e9 Manuel Pozos Castro; el Lic. Jorge Alberto Ram\u00edrez Balderas, director jur\u00eddico de la SEV; el Lic. Eginardo Carde\u00f1a Zavala, jefe del Departamento Patrimonial.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El delegado regional de la SEV en Tuxpan, Prof. On\u00e9simo P\u00e9rez Ramos; el Lic. Jos\u00e9 Alberto Figueroa Gonz\u00e1lez, jefe de Enlace Institucional de la Delegaci\u00f3n Regional de la SEV en Poza Rica; la Lic. Norma Aurelia Guti\u00e9rrez Lara, notaria No. 3 de Tuxpan; y el Prof. Abac\u00fa Hern\u00e1ndez Vicencio, director de secundaria general No. 2 \u201cJos\u00e9 Vasconcelos\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Al dar la bienvenida a las autoridades estatales y regionales, el alcalde Jos\u00e9 Manuel Pozos Castro se\u00f1al\u00f3 que es importante asegurar la titularidad patrimonial de las escuelas, lo que tambi\u00e9n brindar\u00e1 certeza jur\u00eddica a maestros y a comunidades educativas.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cUna escuela con escrituras puede acceder a programas de gobierno para el mejoramiento de su infraestructura f\u00edsica y equipamiento\u201d, destac\u00f3.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Pozos Castro reconoci\u00f3 el reconoci\u00f3 el gran esfuerzo que han venido realizando el Gobierno del Estado y la Secretar\u00eda de Educaci\u00f3n, para escriturar miles de escuelas en todo el Estado de Veracruz: \u201cEsto es el resultado del trabajo coordinado de los 3 niveles de gobierno, de la participaci\u00f3n de directivos, maestros y padres de familia\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cA nosotros como Secretar\u00eda de Educaci\u00f3n de Veracruz nos llena de orgullo que hoy entreguemos estos documentos de propiedad\u201d, indic\u00f3 el Mtro. V\u00edctor Emmanuel Vargas Barrientos, secretario de Educaci\u00f3n del estado de Veracruz.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Dijo que esto se ha logrado gracias al programa \u201cEscuela Garantizada, Escritura Garante\u201d, estrategia que ha posibilitado que las comunidades educativas realicen los tr\u00e1mites para regularizar la situaci\u00f3n jur\u00eddica de las escuelas de forma gratuita.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Agradeci\u00f3 a todos los notarios que han apoyado este programa: \u201ccon su ayuda hemos logrado tener los avances significativos que hemos presentado a los veracruzanos en estos casi 6 a\u00f1os de la administraci\u00f3n del gobernador Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Por su parte, el director jur\u00eddico de la SEV, el Lic. Jorge Alberto Ram\u00edrez Balderas agradeci\u00f3 al gobierno de Tuxpan por el apoyo y las facilidades brindadas para llevar a cabo la entrega.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cLos documentos de propiedad que hoy se entregan forman parte de las acciones tangibles, y el legado con el que el gobierno que encabeza el Ing. Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez cumple con los estudiantes y maestros de nuestro estado, al otorgar certeza y seguridad jur\u00eddica a los inmuebles en los que reciben e imparten sus clases\u201d, mencion\u00f3.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Recalc\u00f3 que estos resultados son posibles gracias al apoyo incondicional y compromiso de los notarios p\u00fablicos: \u201cgracias por el extraordinario trabajo que realizan con la expedici\u00f3n gratuita de las escrituras p\u00fablicas, que se traducen en certidumbre jur\u00eddica para las escuelas de nuestro estado\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En la entrega estuvieron presentes alcaldesas, alcaldes y representantes de ayuntamientos de la zona norte del estado; as\u00ed como titulares de las notar\u00edas p\u00fablicas de Tuxpan, Coatzintla, \u00c1lamo Temapache, Papantla, Cerro Azul.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 El alcalde Jos\u00e9 Manuel Pozos asegur\u00f3 que las escuelas son s\u00edmbolo de esperanza, progreso y transformaci\u00f3n social. En el<\/p>\n","protected":false},"author":4,"featured_media":46008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3205,1082],"tags":[],"class_list":["post-46007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno-tuxpan","category-tuxpan"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2024\/09\/17052c8f-d422-4543-b989-a89c47b54728.jpg?fit=760%2C505&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/46007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=46007"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/46007\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/46008"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=46007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=46007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=46007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}