{"id":52572,"date":"2024-12-17T00:36:32","date_gmt":"2024-12-17T06:36:32","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=52572"},"modified":"2024-12-17T00:36:32","modified_gmt":"2024-12-17T06:36:32","slug":"monreal-y-adan-augusto-salen-de-reunion-con-sheinbaum-sin-declaraciones","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2024\/12\/17\/monreal-y-adan-augusto-salen-de-reunion-con-sheinbaum-sin-declaraciones\/","title":{"rendered":"Monreal y Ad\u00e1n Augusto salen de reuni\u00f3n con Sheinbaum sin declaraciones"},"content":{"rendered":"<p>Los coordinadores de Morena en ambas C\u00e1maras del Congreso de la Uni\u00f3n evitaron dar declaraciones tras su salida de Palacio Nacional, donde fueron citados por la presidenta Claudia Sheinbaum Pardo.<\/p>\n<p>En un encuentro privado, la mandataria federal llam\u00f3 a los legisladores luego del encontronazo que tuvieron a finales de la semana pasada por el ajuste de 123 millones de pesos que la C\u00e1mara de Diputados hizo al presupuesto solicitado por el Senado para 2025. Eso caus\u00f3 un diferendo entre Monreal, presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica en San L\u00e1zaro, y L\u00f3pez Hern\u00e1ndez, presidente de la C\u00e1mara Alta, quienes se han lanzado se\u00f1alamientos mutuos.<\/p>\n<p>Al salir del c\u00f3nclave -que dur\u00f3 alrededor de 40 minutos- ninguno de los legisladores quiso hablar con los reporteros que aguardan alguna declaraci\u00f3n a las afueras del recinto hist\u00f3rico.<\/p>\n<p>Ad\u00e1n Augusto L\u00f3pez sali\u00f3 por la puerta 8 de la calle Corregidora, acompa\u00f1ado por los senadores\u00a0 Ignacio Mier, y el diputado por el PT Juan Ramiro Robledo.\u00a0 Ante la insistencia de los reporteros el presidente del Senado solo dijo: \u201cma\u00f1ana, ma\u00f1ana\u201d.<\/p>\n<p>\u201c\u00bfQu\u00e9 les dijo la presidenta?\u201d, \u201c\u00bfLes jal\u00f3 las orejas?\u201d, fueron algunas preguntas que se lanzaron a L\u00f3pez Hern\u00e1ndez, quien continu\u00f3 caminando sobre la calle de Corregidora hasta encontrar su camioneta sin decir palabra.<\/p>\n<p>En tanto, Monreal sali\u00f3 por la puerta del estacionamiento a bordo de\u00a0 su camioneta, sin siquiera pasar por en frente de los representantes de medios de comunicaci\u00f3n.<\/p>\n<p>Minutos despu\u00e9s, la titular de la Secretar\u00eda de Gobernaci\u00f3n, Rosa Icela Rodr\u00edguez, tambi\u00e9n presente en el encuentro, inform\u00f3 en redes sociales:<\/p>\n<p>\u201cEn conversaci\u00f3n con los compa\u00f1eros coordinadores de los grupos parlamentarios de #Morena en @senadomexicano @adan_augusto y @Mx_Diputados @RicardoMonrealA, se acord\u00f3 que no habr\u00e1 periodo extraordinario para iniciativas pendientes. Nos deseamos feliz Navidad. @Claudiasehin\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los coordinadores de Morena en ambas C\u00e1maras del Congreso de la Uni\u00f3n evitaron dar declaraciones tras su salida de Palacio<\/p>\n","protected":false},"author":4,"featured_media":52573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[],"class_list":["post-52572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2024\/12\/676100a7bcac5.png?fit=1280%2C720&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/52572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=52572"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/52572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/52573"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=52572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=52572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=52572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}