{"id":61674,"date":"2025-04-25T00:17:57","date_gmt":"2025-04-25T06:17:57","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=61674"},"modified":"2025-04-24T21:19:02","modified_gmt":"2025-04-25T03:19:02","slug":"bukele-incurre-en-trata-de-personas-con-migrantes-fiscal-de-venezuela","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2025\/04\/25\/bukele-incurre-en-trata-de-personas-con-migrantes-fiscal-de-venezuela\/","title":{"rendered":"Bukele incurre en \u00abtrata de personas\u00bb con migrantes: fiscal de Venezuela"},"content":{"rendered":"<div id=\"article-content-tts\" class=\"nota-contenido mb-5\">\n<div id=\"content_nitf\">\n<p class=\"nota-justify\">El fiscal general de Venezuela afirm\u00f3 este jueves en entrevista con la AFP que el presidente de El Salvador, Nayib Bukele, incurre en \u00abtrata de personas\u00bb al cobrar dinero para encarcelar a migrantes venezolanos deportados por Estados Unidos.<\/p>\n<p class=\"nota-justify\">\u00abEst\u00e1 cometiendo el delito de trata de personas (&#8230;) est\u00e1 cobrando 7 millones de d\u00f3lares por tener encarcelados a estos venezolanos en El Salvador, es decir, \u00e9l est\u00e1 haciendo un negocio sucio\u00bb, dijo Tarek William Saab, al se\u00f1alar que en alg\u00fan momento \u00abla justicia internacional actuar\u00e1 contra Bukele en este asunto\u00bb.<\/p>\n<p class=\"nota-justify\">Apelando a la Ley de Enemigos Extranjeros de 1798, el gobierno del presidente estadounidense, Donald Trump, deport\u00f3 a El Salvador sin juicio a unos 252 venezolanos a quienes acusa de pertenecer a la pandilla venezolana\u00a0<i>Tren de Aragua<\/i>.<\/p>\n<p class=\"nota-justify\">El Salvador los encerr\u00f3 en el Centro de Confinamiento del Terrorismo (Cecot), una mega prisi\u00f3n de alta seguridad creada por Bukele para pandilleros.<\/p>\n<p class=\"nota-justify\">El Salvador recibir\u00e1 6 millones de d\u00f3lares de Estados Unidos para un grupo inicial de 200 detenidos venezolanos, anunci\u00f3 la Casa Blanca.<\/p>\n<p class=\"nota-justify\">\u00abLa tarifa ser\u00eda relativamente baja para Estados Unidos, pero significativa para nosotros, haciendo sostenible todo nuestro sistema penitenciario\u00bb, afirm\u00f3 Bukele en febrero pasado, sin especificar el monto.<\/p>\n<p class=\"nota-justify\">Las autoridades venezolanas exigen la \u00abliberaci\u00f3n incondicional\u00bb de los venezolanos, un primer grupo de estos trasladados al Cecot el 15 de marzo, argumentando que su detenci\u00f3n y traslado a El Salvador sin juicio es ilegal.<\/p>\n<p class=\"nota-justify\">Exigencia que llega luego de que Bukele ofreciera el pasado domingo 20 de abril un canje de 252 migrantes deportados al Cecot por el mismo n\u00famero de \u00abpresos pol\u00edticos\u00bb en Venezuela.<\/p>\n<p class=\"nota-justify\">Muchos familiares de los detenidos sostienen que no pertenecieron al\u00a0<i>Tren de Aragua<\/i>\u00a0y denuncian que han sido detenidos por tener tatuajes, uno de los criterios utilizados por las autoridades estadounidenses para determinar la pertenencia a esta pandilla.<\/p>\n<p class=\"nota-justify\">Pero Ronna Risquez, autora del libro\u00a0<i>El\u00a0<\/i>Tren de Aragua<i>, la pandilla que revolucion\u00f3 el crimen organizado en Latinoam\u00e9rica<\/i>, afirma que los tatuajes no son una forma de identificar a los miembros de este grupo criminal.<\/p>\n<p class=\"nota-justify\">\u00abEl\u00a0<i>Tren de Aragua<\/i>\u00a0no tiene ning\u00fan tatuaje que lo identifique\u00bb, apunta.<\/p>\n<\/div>\n<\/div>\n<div class=\"notas-relacionadas\"><\/div>\n<div class=\"nota-tags\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El fiscal general de Venezuela afirm\u00f3 este jueves en entrevista con la AFP que el presidente de El Salvador, Nayib<\/p>\n","protected":false},"author":4,"featured_media":61675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[],"class_list":["post-61674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2025\/04\/FISC.jpg?fit=749%2C489&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/61674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=61674"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/61674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/61675"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=61674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=61674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=61674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}