{"id":74401,"date":"2025-11-07T00:13:26","date_gmt":"2025-11-07T06:13:26","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=74401"},"modified":"2025-11-06T23:15:44","modified_gmt":"2025-11-07T05:15:44","slug":"pobladores-defienden-bosques-de-texcoco-detienen-4-camiones-con-madera-de-presunta-tala-ilegal","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2025\/11\/07\/pobladores-defienden-bosques-de-texcoco-detienen-4-camiones-con-madera-de-presunta-tala-ilegal\/","title":{"rendered":"Pobladores defienden bosques de Texcoco; detienen 4 camiones con madera de presunta tala ilegal"},"content":{"rendered":"<p class=\"nota-justify\">Habitantes de la comunidad de Santa Catarina del Monte, en Texcoco, mantienen un frente en defensa de sus bosques y recursos naturales de la monta\u00f1a de la zona para evitar la tala ilegal de madera.<\/p>\n<p class=\"nota-justify\">La tarde noche del mi\u00e9rcoles, los pobladores se movilizaron para interceptar cuatro camiones cargados con madera, con el argumento de que es un actividad il\u00edcita y luego varias horas de tensi\u00f3n, obligaron a los conductores a dejar la carga y les permitieron salir de la localidad.<\/p>\n<p class=\"nota-justify\">El pr\u00f3ximo domingo, los lugare\u00f1os realizar\u00e1n una asamblea con los ejidatarios para determinar sus acciones a seguir para evitar la tala indiscriminada. Las autoridades afirman que existen algunos permisos para realizar dicha acci\u00f3n en la zona.<\/p>\n<p class=\"nota-justify\">La tarde del mi\u00e9rcoles los habitantes detectaron a varios camiones que bajaban de la zona boscosa cargados de troncos. Al dar la voz de alerta, los vecinos se congregaron para impedir se los llevaran aduciendo que se trataba de madera talada ilegalmente.<\/p>\n<p class=\"nota-justify\">D\u00edas antes, los lugare\u00f1os observaron a camiones subir y bajar con madera de manera constante.<\/p>\n<p class=\"nota-justify\">Los habitantes de Santa Catarina del Monte retuvieron cuatro camiones de plataforma cargados de troncos y exigieron que se presentara el due\u00f1o del aserradero a donde iba ser llevado el cargamento.<\/p>\n<p class=\"nota-justify\">Los veh\u00edculos pesados portaban una manta donde se indicaba que la madera era \u201cextracci\u00f3n por saneamiento forestal\u201d, pues ten\u00eda una plaga.<\/p>\n<p class=\"nota-justify\">Los inconformes sostuvieron que esa es una excusa para que empresas sigan talando indiscriminadamente sus bosques.<\/p>\n<p class=\"nota-justify\">\u201cLos camiones ya ten\u00edan d\u00edas bajando con madera de manera indiscriminada. Nosotros como pobladores luchamos por la defensa de nuestros bosques; constantemente hacemos faenas para reforestar y hay zonas que hemos recuperado\u201d, expuso uno de los pobladores.<\/p>\n<p class=\"nota-justify\">\u201cLa tala ilegal es algo delicado porque de aqu\u00ed nacen los manantiales que dan a la parte baja de Texcoco y municipios aleda\u00f1os\u201d, agreg\u00f3.<\/p>\n<p class=\"nota-justify\">Otro de los quejosos mencion\u00f3 que \u201cante lo que est\u00e1 pasando en el pa\u00eds y el mundo de los problemas ambientales, lo que nosotros hacemos es proteger nuestro entorno para beneficio de todos\u201d.<\/p>\n<p class=\"nota-justify\">El director general de seguridad p\u00fablica y movilidad municipal, Roberto Hern\u00e1ndez Romero, explic\u00f3 que al arribar al lugar dialog\u00f3 con los lugare\u00f1os quienes se negaban a liberar los veh\u00edculos.<\/p>\n<p class=\"nota-justify\">Se\u00f1al\u00f3 que tras un di\u00e1logo finalmente accedieron a dejar en libertad a los conductores y camiones a cambio de que dejaran la madera.<\/p>\n<p class=\"nota-justify\">\u201cLa madera fue bajada y dejada en la explanada de la delegaci\u00f3n en resguardo de los pobladores y los camiones fueron liberados. No hubo violencia ni alg\u00fan contratiempo\u201d, resalt\u00f3.<\/p>\n<p class=\"nota-justify\">Los colonos de Santa Mar\u00eda del Monte anunciaron que realizar\u00e1n una asamblea el pr\u00f3ximo domingo para definir las acciones a seguir y pedir a las autoridades una explicaci\u00f3n del por qu\u00e9 se extra\u00eda la madera.<\/p>\n<p class=\"nota-justify\">Santa Catarina del Monte es una de las cinco comunidades enclavadas en la parte alta de la monta\u00f1a de Texcoco; sus habitantes valoran y cuidan sus recursos forestales pues los aprovechan para uso alimentario, artesanal, maderero, medicinal, religioso y flor\u00edstico.<\/p>\n<p class=\"nota-justify\">El acceso al \u00abmonte\u00bb, como le llaman los comuneros a los distintos parajes, no es sencillo; hay que atravesar ca\u00f1adas o subir monta\u00f1as. Es ah\u00ed donde tambi\u00e9n nacen diversos manantiales de agua que surten a las comunidades del l\u00edquido y recarga de los mantos acu\u00edferos de la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Habitantes de la comunidad de Santa Catarina del Monte, en Texcoco, mantienen un frente en defensa de sus bosques y<\/p>\n","protected":false},"author":4,"featured_media":74402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30],"tags":[],"class_list":["post-74401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2025\/11\/TSAL.jpg?fit=522%2C353&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/74401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=74401"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/74401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/74402"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=74401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=74401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=74401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}