{"id":75126,"date":"2025-11-19T01:06:16","date_gmt":"2025-11-19T07:06:16","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=75126"},"modified":"2025-11-19T01:06:16","modified_gmt":"2025-11-19T07:06:16","slug":"ecatepec-y-tlalnepantla-firman-convenio-en-materia-de-seguridad","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2025\/11\/19\/ecatepec-y-tlalnepantla-firman-convenio-en-materia-de-seguridad\/","title":{"rendered":"Ecatepec y Tlalnepantla firman convenio en materia de seguridad"},"content":{"rendered":"<div id=\"article-content-tts\" class=\"nota-contenido mb-5\">\n<div id=\"content_nitf\">\n<p class=\"nota-justify\">Los gobiernos municipales de Ecatepec y Tlalnepantla firmaron un convenio en materia de seguridad para realizar operativos conjuntos,\u00a0fortalecer la prevenci\u00f3n de il\u00edcitos,\u00a0mejorar capacidad de respuesta ante emergencias y optimizar uso de recursos humanos y materiales, con apoyo de Marina y Guardia Nacional.<\/p>\n<p class=\"nota-justify\">La presidenta municipal de Ecatepec, Azucena Cisneros Coss y el alcalde de Tlalnepantla, Raciel P\u00e9rez Cruz signaron el\u00a0convenio ante\u00a0cientos de vecinos de ambos municipios.<\/p>\n<p class=\"nota-justify\">El convenio de seguridad establece optimizar el uso de recursos humanos, materiales y tecnol\u00f3gicos e implementar programas conjuntos de capacitaci\u00f3n y profesionalizaci\u00f3n policial, compartir informaci\u00f3n e inteligencia que permita mejorar la respuesta ante situaciones de riesgo o comisi\u00f3n de delitos.<\/p>\n<p class=\"nota-justify\">La alcaldesa se\u00f1al\u00f3 que es\u00a0importante poder consolidar con Tlalnepantla una coordinaci\u00f3n que ya se ha estado trabajando, sobre todo en las\u00a0partes altas donde se necesita hacer doble muro, intercambiar estrategias, informaci\u00f3n, inteligencia e investigaci\u00f3n.<\/p>\n<p class=\"nota-justify\">\u201cPara la vida de las personas no hay fronteras y con este acuerdo habr\u00e1 coordinaci\u00f3n para implementar operativos en conjunto entre ambos municipios con el respaldo de Fuerza de Tarea Marina y fuerzas federales, que forman parte del Mando Coordinado, la estrategia que impuls\u00f3 la presidenta de la Rep\u00fablica Claudia Sheinbaum, para visibilizar a la Zona Oriente que coordina estrategias de inteligencia e investigaci\u00f3n con los tres niveles de gobierno para bajar los delitos\u201d.<\/p>\n<p class=\"nota-justify\">\u201cEn Ecatepec no hay parang\u00f3n de los a\u00f1os pasados, en los que gobern\u00f3 gente que consinti\u00f3 y toler\u00f3 delincuencia en la calle, por eso hoy estamos atacando en conjunto, los tres niveles de gobierno, a todo lo que tiene que ver con la delincuencia y los criminales, esto no va a parar ah\u00ed, porque vienen m\u00e1s operativos de estrategia que est\u00e1n bajando las autoridades federales\u201d, dijo.<\/p>\n<p class=\"nota-justify\">En su intervenci\u00f3n, el presidente municipal de Tlalnepantla, Raciel P\u00e9rez destac\u00f3 que comparte una frontera dif\u00edcil con Ecatepec y ambo municipios enfrentan un antecedente similar como que en el pasado prevalecieron intereses ajenos, por eso combatir la delincuencia tambi\u00e9n implica depurar las corporaciones.<\/p>\n<p class=\"nota-justify\">\u201cHay una ciudadan\u00eda que juzga y exige con severidad, por eso celebramos con determinaci\u00f3n la firma de este convenio y reconozco a la presidenta municipal de Ecatepec su voluntad, est\u00e1 consciente de la problem\u00e1tica que plantea una frontera tan dif\u00edcil como es la de Tlalnepantla y Ecatepec\u201d, expres\u00f3.<\/p>\n<p class=\"nota-justify\">El Comisario de Seguridad Ciudadana y Tr\u00e1nsito de Ecatepec, Edgar Machado Pe\u00f1a afirm\u00f3 que este acuerdo fortalece la estrategia de Mando Unificado que ha permitido la reducci\u00f3n de \u00edndices delictivos mediante la proximidad social, prevenci\u00f3n de il\u00edcitos y atenci\u00f3n a delitos de alto impacto como el robo de veh\u00edculos<\/p>\n<p>\u201cCon este acuerdo podemos fortalecer las actividades del mando unificado y por su puesto las actividades de Marina en Tlalnepantla podr\u00e1n fortalecerse, estamos dando este mensaje de solidaridad y de uni\u00f3n de lo que hemos venido construyendo desde el inicio de esta administraci\u00f3n, un pueblo seguro y en paz, y un verdadero cambio\u201d, puntualiz\u00f3.<\/p>\n<\/div>\n<\/div>\n<div class=\"notas-relacionadas\"><\/div>\n<div class=\"nota-tags\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los gobiernos municipales de Ecatepec y Tlalnepantla firmaron un convenio en materia de seguridad para realizar operativos conjuntos,\u00a0fortalecer la prevenci\u00f3n<\/p>\n","protected":false},"author":4,"featured_media":75127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30],"tags":[],"class_list":["post-75126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2025\/11\/CHUL-1.jpg?fit=782%2C518&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/75126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=75126"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/75126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/75127"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=75126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=75126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=75126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}