{"id":75296,"date":"2025-11-21T00:49:59","date_gmt":"2025-11-21T06:49:59","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=75296"},"modified":"2025-11-21T00:49:59","modified_gmt":"2025-11-21T06:49:59","slug":"ucrania-recibio-de-eu-el-borrador-del-plan-de-paz-con-rusia","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2025\/11\/21\/ucrania-recibio-de-eu-el-borrador-del-plan-de-paz-con-rusia\/","title":{"rendered":"Ucrania recibi\u00f3 de EU el borrador del plan de paz con Rusia"},"content":{"rendered":"<p class=\"nota-justify\">Mientras la oficina del presidente de Ucrania confirm\u00f3 este jueves que Volodymir Zelensky \u201crecibi\u00f3 oficialmente de Estados Unidos un borrador de plan que, seg\u00fan la evaluaci\u00f3n de la parte estadunidense, puede ayudar a revitalizar la diplomacia\u201d, el Kremlin eludi\u00f3 emitir una opini\u00f3n sobre un documento que nadie ha visto y todos comentan con base en fuentes an\u00f3nimas.<\/p>\n<p class=\"nota-justify\">\u201cEn los pr\u00f3ximos d\u00edas el presidente de Ucrania espera hablar con el presidente (Donald) Trump de las oportunidades diplom\u00e1ticas existentes y de los puntos clave requeridos para lograr la paz\u201d, dice el comunicado, que no hace menci\u00f3n alguna de Rusia, y concluye:<\/p>\n<p class=\"nota-justify\">\u201cEstamos listos ahora, igual que antes, para trabajar de forma constructiva con la parte estadunidense y con nuestros socios en Europa y en el mundo para que el resultado sea la paz\u201d.<\/p>\n<p class=\"nota-justify\">En contraste, el Kremlin eludi\u00f3 responder a los reporteros que piensa sobre el \u201cplan de paz\u201d de Trump:<\/p>\n<p class=\"nota-justify\">\u201cConsultas como tales no existen al d\u00eda de hoy (jueves). Contactos, sin duda, s\u00ed los hay\u201d, contest\u00f3 as\u00ed el vocero de la presidencia rusa, Dimitri Peskov, dando la raz\u00f3n de modo salom\u00f3nico a los dos personajes del entorno presidencial que se disputan el derecho a liderar las negociaciones con Estados Unidos: el canciller Serguei Lavrov y Kiril Dmitriev, el enviado econ\u00f3mico del presidente Vladimir Putin.<\/p>\n<p class=\"nota-justify\">La dependencia de Lavrov, desde que la prensa internacional empez\u00f3 a filtrar fragmentos del supuesto plan de 28 puntos, ha insistido en que Rusia no ha recibido de manera oficial ning\u00fan documento o propuesta de Estados Unidos.<\/p>\n<p class=\"nota-justify\">Dmitriev, en cambio, da a entender en redes sociales que el documento es resultado de su gesti\u00f3n con Steve Witkoff, enviado especial de Trump, y que su visita a Estados Unidos, al margen de la canciller\u00eda, cay\u00f3 en terreno f\u00e9rtil por el esc\u00e1ndalo de corrupci\u00f3n que debilita al gobierno de Zelensky.<\/p>\n<p class=\"nota-justify\">Peskov, como hizo la v\u00edspera, se neg\u00f3 a comentar el plan de Trump: \u201cPuedo decir s\u00f3lo lo que repet\u00ed ayer (mi\u00e9rcoles) en varias ocasiones: no puedo a\u00f1adir nada nuevo a lo que se habl\u00f3 en Anchorage (Alaska, donde se celebr\u00f3 la cumbre de Putin y Trump). No hay nada nuevo, aunque cualquier momento es bueno para un arreglo pol\u00edtico\u201d.<\/p>\n<p class=\"nota-justify\">Zelensky se reuni\u00f3 este jueves con una delegaci\u00f3n del Pent\u00e1gono que visita el vecino pa\u00eds eslavo, ocasi\u00f3n que \u2013seg\u00fan la oficina de la presidencia ucrania\u2013 aprovech\u00f3 para enfatizar los principios que deben tenerse en cuenta para Ucrania y \u201clas partes acordaron trabajar en los puntos del plan para que pueda llevar a un final justo de la guerra\u201d.<\/p>\n<p class=\"nota-justify\">En cambio, de manera no oficial en Ucrania, a trav\u00e9s de declaraciones de expertos y textos period\u00edsticos, lo que se ha filtrado del plan de Trump provoca un rechazo absoluto, pues \u2013coinciden casi todos\u2013 \u201cnadie en su sano juicio puede aceptar el cat\u00e1logo de exigencias maximalistas\u201d de Rusia que equivalen a pedir la capitulaci\u00f3n completa de Ucrania, que adem\u00e1s se quedar\u00eda desarmada ante eventuales \u201cagresiones futuras\u201d.<\/p>\n<p class=\"nota-justify\">De acuerdo con fuentes an\u00f3nimas estadunidenses, este plan de 28 puntos se inspira en el plan de 20 puntos sobre Gaza y, entre otros aspectos, incluye entregar a Rusia la totalidad del Donb\u00e1s (las regiones de Donietsk y Lugansk, que ser\u00edan declaradas zona desmilitarizada), y Kiev tendr\u00eda que reducir sus fuerzas armadas dos veces y media no sobrepasando el l\u00edmite de 200 mil efectivos; en tanto Rusia tendr\u00eda que devolver a Ucrania las partes ocupadas de Jers\u00f3n y Zaporiyia.<\/p>\n<p class=\"nota-justify\">Esto \u00faltimo, en vista de que el Kremlin ya incorpor\u00f3 tambi\u00e9n la totalidad de Jers\u00f3n y Zaporiyia a la Constituci\u00f3n como parte inalienable de la Federaci\u00f3n Rusa, tampoco parece que sea aceptable para Mosc\u00fa.<\/p>\n<p class=\"nota-justify\">En realidad, consideran analistas, mientras no se publique el plan de Trump completo mucho de lo que ahora \u201ctrasciende\u201d puede quedar fuera de la versi\u00f3n final del documento, si es que llega a consensuarse entre quienes realmente importa: rusos y ucranios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras la oficina del presidente de Ucrania confirm\u00f3 este jueves que Volodymir Zelensky \u201crecibi\u00f3 oficialmente de Estados Unidos un borrador<\/p>\n","protected":false},"author":4,"featured_media":75297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[],"class_list":["post-75296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2025\/11\/uk.jpg?fit=886%2C483&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/75296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=75296"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/75296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/75297"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=75296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=75296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=75296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}