{"id":75408,"date":"2025-11-24T00:08:39","date_gmt":"2025-11-24T06:08:39","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=75408"},"modified":"2025-11-23T23:36:46","modified_gmt":"2025-11-24T05:36:46","slug":"lider-del-pan-no-descarta-a-salinas-pliego-como-su-candidato-presidencial","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2025\/11\/24\/lider-del-pan-no-descarta-a-salinas-pliego-como-su-candidato-presidencial\/","title":{"rendered":"L\u00edder del PAN no descarta a Salinas Pliego como su candidato presidencial"},"content":{"rendered":"<p class=\"nota-justify\">El dirigente nacional del Partido Acci\u00f3n Nacional (PAN), Jorge Romero Herrera, no descart\u00f3 que en 2030 el empresario y due\u00f1o de Tv Azteca y Elektra, Ricardo Salinas Pliego, sea candidato presidencial del\u00a0<i>blanquiazul<\/i>, declaraci\u00f3n que no ha generado reacciones entre el panismo. Tampoco Salinas Pliego se ha pronunciado al respecto.<\/p>\n<p class=\"nota-justify\">En una entrevista con el peri\u00f3dico\u00a0<i>El Pa\u00eds<\/i>\u00a0de Espa\u00f1a, Romero Herrera, y a una pregunta expresa respecto de qu\u00e9 aspirantes no panistas considera para representar a ese partido, Romero Herrera respondi\u00f3:<\/p>\n<p class=\"nota-justify\">\u201cA Ricardo Salinas Pliego lo veo con perfecta claridad. Si \u00e9l se anima, avanza y vemos que va creciendo en el \u00e1nimo, por supuesto que no lo descartamos. No descartamos a nadie\u201d.<\/p>\n<p class=\"nota-justify\">Apenas el 13 de noviembre, la Suprema Corte de Justicia de la Naci\u00f3n resolvi\u00f3 de manera definitiva lo nueve juicios fiscales -algunos hasta de 16 a\u00f1os de antig\u00fcedad- que Salinas Pliego interpuso para eludir el pago de impuestos.<\/p>\n<p class=\"nota-justify\">Los ministros aprobaron por unanimidad las sentencias que obligan a sus empresas a liquidar cr\u00e9ditos fiscales por 48 mil 326 millones 928 mil pesos. Adem\u00e1s, enfrenta procesos en Estados Unidos por la falta de pago por los bonos que Tv Azteca emiti\u00f3 en 2017, que suman un adeudo de 600 millones de d\u00f3lares.<\/p>\n<p class=\"nota-justify\">En la entrevista con el rotativo espa\u00f1ol, a Jorge Romero tambi\u00e9n se le pregunt\u00f3 si su partido ya tiene un candidato presidencial panista para 2030. Contest\u00f3: \u201cMaru Campos en Chihuahua, Libia Garc\u00eda en Guanajuato, Tere Jim\u00e9nez en Aguascalientes, Mauricio Kuri en Quer\u00e9taro. A Ricardo Anaya lo conoce todo el pa\u00eds, ya fue candidato presidencial. Hay un gran exgobernador, Mauricio Vila. Si Margarita Zavala levantara la mano, pero s\u00faper absolutamente claro que s\u00ed. Tenemos perfiles de sobra y no nos cerramos a los externos\u201d.<\/p>\n<p class=\"nota-justify\">El dirigente del blanquiazul tambi\u00e9n se refiri\u00f3 a las alianzas con otros partidos. Descart\u00f3 las coaliciones como las que ya acudi\u00f3 a elecciones con el Partido Revolucionario Institucional y el extinto Partido de la Revoluci\u00f3n Democr\u00e1tica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dirigente nacional del Partido Acci\u00f3n Nacional (PAN), Jorge Romero Herrera, no descart\u00f3 que en 2030 el empresario y due\u00f1o<\/p>\n","protected":false},"author":4,"featured_media":75409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[33],"tags":[],"class_list":["post-75408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2025\/11\/586564630_1261509616002143_2898601100149336438_n.jpg?fit=1200%2C800&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/75408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=75408"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/75408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/75409"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=75408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=75408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=75408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}