{"id":76458,"date":"2025-12-10T00:05:02","date_gmt":"2025-12-10T06:05:02","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=76458"},"modified":"2025-12-09T22:24:26","modified_gmt":"2025-12-10T04:24:26","slug":"diputados-avalan-en-lo-particular-prohibicion-de-vapeadores-excluyen-a-usuarios-de-sanciones","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2025\/12\/10\/diputados-avalan-en-lo-particular-prohibicion-de-vapeadores-excluyen-a-usuarios-de-sanciones\/","title":{"rendered":"Diputados avalan en lo particular prohibici\u00f3n de vapeadores; excluyen a usuarios de sanciones"},"content":{"rendered":"<p class=\"nota-justify\">Con el agregado de una reserva presentada por el bloque de mayor\u00eda, para especificar que no se sancionar\u00e1 a quienes usen o tengan un vapeador, la C\u00e1mara de Diputados aprob\u00f3 en lo particular la reforma a la Ley General de Salud que proh\u00edbe totalmente el uso de esos dispositivos, as\u00ed como de otros tipos de cigarrillos electr\u00f3nicos, incluidos los que calientan tabaco o vaporizan cualquier sustancia t\u00f3xica.<\/p>\n<p class=\"nota-justify\">Luego de una larga serie de 71 oradores enlistados a presentar reservas, la enmienda fue aprobada por 292 votos en favor, de Morena y la mayor parte de sus legisladores aliados, y 163 en contra, de PRI, PAN y MC, a los cuales se sumaron 30 sufragios en contra de diputados del PT y uno de Julio Scherer Parey\u00f3n, del PVEM. El impacto de regular este tema gener\u00f3 un debate que se extendi\u00f3, en total, por casi nueve horas.<\/p>\n<p>El tema evidenci\u00f3 la divisi\u00f3n del PT, porque un sector de 30 parlamentarios vot\u00f3 por la instrucci\u00f3n que dio el dirigente nacional del partido, Alberto Anaya, de votar en contra, y tras una discusi\u00f3n interna, se dej\u00f3 el voto libre. De esa forma, 10 legisladores \u2013incluido el coordinador, Reginaldo Sandioval\u2014votaron a favor.<\/p>\n<p class=\"nota-justify\"><strong>No se busca criminalizar: Morena<\/strong><\/p>\n<p class=\"nota-justify\">Para aclarar ese aspecto, el coordinador de la bancada de Morena en San L\u00e1zaro, Ricardo Monreal \u00c1vila, subi\u00f3 a tribuna para presentar una reserva, en conjunto con su correligionario Pedro Zenteno, presidente de la Comisi\u00f3n de Salud, y la petista Margarita Garc\u00eda, mediante la cual se especificaron los alcances de las sanciones.<\/p>\n<p class=\"nota-justify\">\u201cVamos a modificar el art\u00edculo 282, para que no existan efectos sancionadores a los usuarios, porque el verdadero objetivo no es castigar el consumo personal; nuestro objetivo era desmantelar el mercado que produce, distribuye y obtiene ganancias impresionantes, millonarias, en detrimento de la salud de los j\u00f3venes\u201d, puntualiz\u00f3.<\/p>\n<p class=\"nota-justify\">De esta forma, recalc\u00f3, se le a\u00f1ade un p\u00e1rrafo al art\u00edculo 282 qu\u00e1ter, para especificar que \u201cqueda prohibido en todo el territorio nacional la adquisici\u00f3n con fines de comercializaci\u00f3n. Se except\u00faa de la prohibici\u00f3n su consumo y posesi\u00f3n\u201d.<\/p>\n<p class=\"nota-justify\">Con ello, explic\u00f3 el tambi\u00e9n presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica, \u201csi una persona est\u00e1 consumiendo o incluso trae en posesi\u00f3n uno o dos cigarrillos electr\u00f3nicos, no es delito y no va a ser sancionada ninguna persona\u201d.<\/p>\n<p class=\"nota-justify\">Monreal asever\u00f3 que lo anterior tiene un efecto jur\u00eddico directo sobre el art\u00edculo 456 Bis, y admiti\u00f3 que \u201ccomo est\u00e1 ahorita la disposici\u00f3n, puede prestarse a confusi\u00f3n y que (dicho apartado) establece las penas de prisi\u00f3n y las multas para aquel que adquiera\u201d un vapeador.<\/p>\n<p class=\"nota-justify\">\u201cSin esta precisi\u00f3n \u2013acept\u00f3&#8211; pudiera interpretarse que hasta para el que consuma o el que tenga en posesi\u00f3n\u201d habr\u00eda castigo. \u201cPor eso, estamos clarificando este r\u00e9gimen sancionador. Que quede estrictamente limitado a quienes participan en el negocio de los vapeadores y no a las personas usuarias\u201d.<\/p>\n<p class=\"nota-justify\">Asimismo, se incluy\u00f3 en el citado art\u00edculo 282 qu\u00e1ter que no solo los cigarrillos electr\u00f3nicos, vapeadores y dem\u00e1s sistemas o dispositivos an\u00e1logos quedan prohibidos, \u201csino que incluimos aquellos que son desechables en un solo uso\u201d.<\/p>\n<p class=\"nota-justify\">Por todo lo anterior, dijo, \u201ccon las modificaciones que hoy someto a su consideraci\u00f3n, queda jur\u00eddicamente blindado que el consumo y la posesi\u00f3n para uso personal no constituyan infracci\u00f3n alguna, solamente aquellos que producen, consumen, comercializan y obtienen lucro indebido de ello son los que van a ser sancionados\u201d.<\/p>\n<p class=\"nota-justify\">En la reserva tambi\u00e9n se incluyeron adecuaciones al art\u00edculo 282 Ter, que se refiere a la definici\u00f3n de cigarrillos electr\u00f3nicos, vapeadores y dem\u00e1s sistemas o dispositivos an\u00e1logos, como todo aparato con sistema mec\u00e1nico, electr\u00f3nico o de cualquier tecnolog\u00eda que se utilice para calentar, vaporizar y atomizar sustancias t\u00f3xicas.<\/p>\n<p class=\"nota-justify\">En ese apartado, se agreg\u00f3 a las \u201csustancias l\u00edquidas, geles, sales, ceras, aerosoles secos, resinas, aceites cerosos u otras formulaciones sint\u00e9ticas con o sin nicotina, susceptible de ser inhaladas por las personas consumidoras\u201d, con el objetivo de \u201ccerrar el vac\u00edo probable y no dejar una f\u00f3rmula ambigua\u201d.<\/p>\n<p class=\"nota-justify\">El ex gobernador de Zacatecas revel\u00f3 que \u201ca m\u00ed tambi\u00e9n me visitaron los cabilderos (de las empresas productoras de los vapeadores y sus cartuchos) e insistieron mucho, no me convencieron. Por m\u00e1s alegatos u ofrecimientos, no me convencieron\u201d, debido a que seg\u00fan estudios oficiales, hay al menos medio mill\u00f3n de ni\u00f1os y adolescentes que ya son usuarios de cigarrillos electr\u00f3nicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el agregado de una reserva presentada por el bloque de mayor\u00eda, para especificar que no se sancionar\u00e1 a quienes<\/p>\n","protected":false},"author":4,"featured_media":76459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[33],"tags":[],"class_list":["post-76458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2025\/12\/DPTDS.jpg?fit=1200%2C801&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/76458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=76458"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/76458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/76459"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=76458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=76458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=76458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}