{"id":77872,"date":"2026-01-09T00:09:48","date_gmt":"2026-01-09T06:09:48","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=77872"},"modified":"2026-01-08T23:26:53","modified_gmt":"2026-01-09T05:26:53","slug":"china-frena-exportaciones-de-tierras-raras-a-empresas-japonesas-medios","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/01\/09\/china-frena-exportaciones-de-tierras-raras-a-empresas-japonesas-medios\/","title":{"rendered":"China frena exportaciones de tierras raras a empresas japonesas: medios"},"content":{"rendered":"<p class=\"nota-justify\">China empez\u00f3 a restringir las exportaciones de tierras raras y \u200cpotentes imanes que las contienen a empresas japonesas, inform\u00f3 el jueves el diario\u00a0<i>The Wall Street Journal\u00a0<\/i>(WSJ), despu\u00e9s de que Pek\u00edn prohibi\u00f3 las exportaciones de productos de uso dual al ej\u00e9rcito japon\u00e9s.<\/p>\n<p class=\"nota-justify\">Las restricciones chinas se aplican en general a todas las industrias japonesas y no se limitan a la industria de defensa, se\u00f1al\u00f3 el\u00a0<i>Journal<\/i>. El Ministerio de Comercio chino dijo el \u200cjueves que la \u2060prohibici\u00f3n de exportar productos de uso dual a Jap\u00f3n s\u00f3lo afectar\u00e1 a las empresas militares.<\/p>\n<p class=\"nota-justify\">\u201cLos usuarios civiles no se ver\u00e1n afectados\u201d, afirm\u00f3 a la prensa He Yadong, \u200cportavoz del Ministerio de Comercio.<\/p>\n<p class=\"nota-justify\">El martes, China anunci\u00f3 una amplia prohibici\u00f3n de la exportaci\u00f3n a Jap\u00f3n de los denominados productos de \u200duso dual con posibles aplicaciones militares.<\/p>\n<p class=\"nota-justify\">El\u00a0<i>WSJ\u00a0<\/i>inform\u00f3 \u200dde que, desde el martes, China empez\u00f3 a restringir las exportaciones \u2060a empresas japonesas de tierras raras \u201cpesadas\u201d, as\u00ed como de los potentes imanes que las contienen, citando a dos exportadores de China.<\/p>\n<p class=\"nota-justify\">El\u00a0<i>Journal<\/i>\u00a0cit\u00f3 a otra persona an\u00f3nima familiarizada con las decisiones del gobierno chino, que afirm\u00f3 que la revisi\u00f3n de las solicitudes de licencias de exportaci\u00f3n en toda la industria japonesa se ha detenido y no s\u00f3lo se dirige a las empresas japonesas de \u2060defensa.<\/p>\n<p class=\"nota-justify\">Los productos de doble uso son bienes, software o tecnolog\u00edas que tienen aplicaciones tanto civiles como militares. Entre ellos se incluyen ciertos imanes de tierras raras que accionan motores en piezas de autom\u00f3viles como retrovisores laterales, altavoces y bombas de aceite.<\/p>\n<p class=\"nota-justify\">Reuters no pudo confirmar de inmediato el informe. Los ministerios de Comercio y de Relaciones Exteriores de China \u200cno respondieron inmediatamente a las peticiones de Reuters \u200cpara comentar el informe del\u00a0<i>Journal<\/i>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>China empez\u00f3 a restringir las exportaciones de tierras raras y \u200cpotentes imanes que las contienen a empresas japonesas, inform\u00f3 el<\/p>\n","protected":false},"author":4,"featured_media":77873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2050],"tags":[],"class_list":["post-77872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/01\/CHINNN.jpg?fit=1200%2C776&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/77872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=77872"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/77872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/77873"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=77872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=77872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=77872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}