{"id":77893,"date":"2026-01-09T00:16:47","date_gmt":"2026-01-09T06:16:47","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=77893"},"modified":"2026-01-08T23:45:33","modified_gmt":"2026-01-09T05:45:33","slug":"yucatan-mantiene-la-tasa-de-homicidios-mas-baja-del-pais-en-2025","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/01\/09\/yucatan-mantiene-la-tasa-de-homicidios-mas-baja-del-pais-en-2025\/","title":{"rendered":"Yucat\u00e1n mantiene la tasa de homicidios m\u00e1s baja del pa\u00eds en 2025"},"content":{"rendered":"<p class=\"nota-justify\">Yucat\u00e1n se mantiene como la entidad con la cifra total de homicidios m\u00e1s baja a nivel nacional, apenas el 0.1 por ciento, registrada durante 2025, inform\u00f3 hoy Marcela Figueroa Franco, titular del Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica.<\/p>\n<p class=\"nota-justify\">Durante \u201cLa Ma\u00f1anera del Pueblo\u201d, con la presencia de la presidenta Claudia Sheinbaum, la funcionaria dijo que el informe corresponde a los delitos registrados durante el a\u00f1o pasado donde la entidad yucateca mantiene sus niveles de seguridad.<\/p>\n<p class=\"nota-justify\">Con corte al 31 de diciembre de 2025, Yucat\u00e1n registr\u00f3 0.1 por ciento con 33 carpetas de investigaci\u00f3n iniciadas por delitos dolosos, en tanto que otras siete entidades concentran el 50.5 por ciento de los homicidios de este nivel cometidos en el pa\u00eds: Guanajuato, Chihuahua, Baja California, Sinaloa, Estado de M\u00e9xico, Guerrero y Michoac\u00e1n.<\/p>\n<p class=\"nota-justify\">Adem\u00e1s, durante el a\u00f1o pasado, Yucat\u00e1n \u2013con el gobierno de Joaqu\u00edn D\u00edaz Mena- disminuy\u00f3 24.8 por ciento el registro de homicidios dolosos en comparaci\u00f3n con lo registrado en 2024, de acuerdo con el reporte de Figueroa Franco.<\/p>\n<p class=\"nota-justify\">Y siempre en cuanto homicidios dolosos, las cifras emitidas oficialmente en 2025 por el Secretariado de Seguridad Estatal indican que Yucat\u00e1n ocup\u00f3 el 1er. lugar con menor tasa de homicidios dolosos por cada 100 mil habitantes al registrar 1.03, tasa 12 veces menor al dato nacional de 12.85 homicidios dolosos por cada 100 mil habitantes.<\/p>\n<p class=\"nota-justify\">Adem\u00e1s, se ubic\u00f3 en el 2do. lugar con mayor confianza de su poblaci\u00f3n hacia la polic\u00eda estatal con 71.1%, dato superior al nacional de 57.1%. Asimismo, qued\u00f3 en el 3er. lugar con mayor percepci\u00f3n de seguridad con 59.8%, dato 2 veces mayor a la percepci\u00f3n nacional de 23.2.<\/p>\n<p class=\"nota-justify\">Entre otras estrategias, Yucat\u00e1n fortaleci\u00f3 su infraestructura de seguridad vehicular con 585 automotores adquiridos, de los cuales, 391 son para la Secretar\u00eda de Seguridad P\u00fablica (SSP), integrados por 313 camionetas, 34 autom\u00f3viles y 44 motocicletas, destinados a fortalecer la operaci\u00f3n y capacidad de respuesta de la Polic\u00eda estatal.<\/p>\n<p class=\"nota-justify\">En los puestos de Control en M\u00e9rida, en 2025 se efectuaron m\u00e1s de 2 mil operativos de seguridad ciudadana y m\u00e1s de 2,600 acciones conjuntas de prevenci\u00f3n del delito, adem\u00e1s de la instalaci\u00f3n de m\u00e1s de 10 mil puestos de control en carreteras donde se verificaron m\u00e1s de 29 mil veh\u00edculos. Como resultado: detenci\u00f3n de 5 mil 500 personas por delitos de diversa \u00edndole.<\/p>\n<p class=\"nota-justify\">Tambi\u00e9n se realizaron, el a\u00f1o pasado, m\u00e1s de 14 mil operativos de seguridad y se instalaron casi 6 mil puestos de control con saldo superior a 12 mil personas detenidas por distintos il\u00edcitos, como muestra del combate a la delincuencia en la capital yucateca.<\/p>\n<p class=\"nota-justify\">Y la Polic\u00eda estatal estren\u00f3 m\u00e1s de 51 mil prendas t\u00e1cticas y m\u00e1s de mil chalecos antibalas de doble blindaje para personal operativo de las \u00e1reas de polic\u00eda preventiva y de investigaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yucat\u00e1n se mantiene como la entidad con la cifra total de homicidios m\u00e1s baja a nivel nacional, apenas el 0.1<\/p>\n","protected":false},"author":4,"featured_media":77894,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30],"tags":[],"class_list":["post-77893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/01\/YUPOL.jpg?fit=1200%2C739&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/77893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=77893"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/77893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/77894"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=77893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=77893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=77893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}