{"id":77922,"date":"2026-01-10T00:02:31","date_gmt":"2026-01-10T06:02:31","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=77922"},"modified":"2026-01-09T20:02:18","modified_gmt":"2026-01-10T02:02:18","slug":"ayuntamiento-y-dif-municipal-llevan-festejo","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/01\/10\/ayuntamiento-y-dif-municipal-llevan-festejo\/","title":{"rendered":"Ayuntamiento y DIF Municipal llevan festejo"},"content":{"rendered":"<p>El H. Ayuntamiento de Tuxpan, en coordinaci\u00f3n con el Sistema para el Desarrollo Integral de la Familia (DIF) Municipal, llev\u00f3 regalos y momentos de convivencia a la ni\u00f1ez de Laja de Colom\u00e1n y de diversas comunidades aleda\u00f1as, como parte de los festejos con motivo del D\u00eda de Reyes.<\/p>\n<p>Este segundo festejo se desarroll\u00f3 en un ambiente de alegr\u00eda y cercan\u00eda, reuniendo a familias provenientes de Tronconal, El Salto, Alto de San Lorenzo, La Camelia, Nueva Esperanza, Banderas, Sabanillas, H\u00e9roes de Nacozari, Baltazar, Zapote Bueno, Buenavista, Juan Zumaya y Palma Morelos, fortaleciendo el v\u00ednculo comunitario y la convivencia familiar.<\/p>\n<p>El presidente municipal, Daniel Cortina Mart\u00ednez, acompa\u00f1ado por la presidenta del DIF Tuxpan, Marisol Mart\u00ednez Barrios; la s\u00edndica \u00fanica, Martha Laura Z\u00e1rate Vicencio; integrantes del Cabildo y agentes municipales de las localidades invitadas, comparti\u00f3 una grata tarde con las y los asistentes.<\/p>\n<p>El alcalde reiter\u00f3 su compromiso de trabajar de manera cercana y sin distinciones, destacando la importancia del trabajo conjunto entre instituciones, y felicit\u00f3 al DIF Municipal por impulsar estas iniciativas que continuar\u00e1n llegando a diversas comunidades del municipio durante la semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El H. Ayuntamiento de Tuxpan, en coordinaci\u00f3n con el Sistema para el Desarrollo Integral de la Familia (DIF) Municipal, llev\u00f3<\/p>\n","protected":false},"author":4,"featured_media":77923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1082],"tags":[],"class_list":["post-77922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tuxpan"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/01\/REY.jpg?fit=1200%2C800&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/77922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=77922"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/77922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/77923"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=77922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=77922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=77922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}