{"id":80331,"date":"2026-02-20T00:10:19","date_gmt":"2026-02-20T06:10:19","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=80331"},"modified":"2026-02-19T23:16:26","modified_gmt":"2026-02-20T05:16:26","slug":"fitch-destacan-bancos-grandes-por-rentabilidad-y-altos-niveles-de-capitalizacion","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/02\/20\/fitch-destacan-bancos-grandes-por-rentabilidad-y-altos-niveles-de-capitalizacion\/","title":{"rendered":"Fitch: destacan bancos grandes por rentabilidad y altos niveles de capitalizaci\u00f3n"},"content":{"rendered":"<div id=\"article-content-tts\" class=\"nota-contenido mb-5\">\n<div id=\"content_nitf\">\n<p class=\"nota-justify\">Los bancos m\u00e1s grandes del pa\u00eds registran rentabilidad, colchones de capital superiores a los que pide la regulaci\u00f3n y capacidad para absorber las p\u00e9rdidas, inform\u00f3 la calificadora Fitch.<\/p>\n<p class=\"nota-justify\">En un documento del sector, destac\u00f3 que los grandes bancos entran al 2026 con m\u00e1s cautela a medida que las tasas de inter\u00e9s se normalizan y persiste la incertidumbre en torno a la renegociaci\u00f3n del acuerdo comercial entre Estados Unidos, M\u00e9xico y Canad\u00e1 (T-MEC) y la pol\u00edtica comercial de Estados Unidos.<\/p>\n<p class=\"nota-justify\">Dijo que en el cuarto trimestre del 2025, el financiamiento basado en dep\u00f3sitos y los ingresos por comisiones respaldaron la rentabilidad de los bancos.<\/p>\n<p class=\"nota-justify\">\u201cEl capital y la liquidez se mantuvieron s\u00f3lidos a pesar de un entorno de tasas menos favorable. La optimizaci\u00f3n del costo de financiamiento y una alta proporci\u00f3n de dep\u00f3sitos a la vista protegieron los m\u00e1rgenes en algunos bancos\u201d, detall\u00f3 la firma.<\/p>\n<p class=\"nota-justify\">BBVA mantuvo su liderazgo en dep\u00f3sitos (los dep\u00f3sitos aumentaron un 10.3 por ciento en 2025), mientras que Banorte mantuvo una mezcla estable de 70 por ciento de dep\u00f3sitos a la vista y 30 por ciento de dep\u00f3sitos a plazo. En tanto, Santander report\u00f3 un crecimiento de dep\u00f3sitos de 7.3 por ciento en 2025, respaldado tanto por dep\u00f3sitos a la vista como a plazo, lo que refleja una base de fondeo diversificada.<\/p>\n<p class=\"nota-justify\">\u201cLa diferencia en la migraci\u00f3n de la calidad de los activos se hizo m\u00e1s evidente, incluso cuando los \u00edndices de morosidad del sector se mantuvieron s\u00f3lidos, en 2.2 por ciento al cuarto trimestre del 2025\u201d, indic\u00f3,<\/p>\n<p class=\"nota-justify\">La utilidad neta de BBVA M\u00e9xico en 2025 aument\u00f3 6.2 por ciento, impulsada por m\u00e1rgenes m\u00e1s s\u00f3lidos, mayores ingresos por comisiones y mejores resultados de intermediaci\u00f3n\/comercializaci\u00f3n.<\/p>\n<p class=\"nota-justify\">En Banorte, el resultado neto aument\u00f3 5 por ciento interanual, impulsado por un crecimiento del margen financiero, una expansi\u00f3n de dos d\u00edgitos de los ingresos no financieros, costos operativos controlados y menores costos de financiamiento.<\/p>\n<p class=\"nota-justify\">A su vez, la ganancia neta de Santander M\u00e9xico aument\u00f3 25.8 por ciento interanual gracias a un mayor margen financiero, comisiones, y menores provisiones.<\/p>\n<p class=\"nota-justify\">Sin embargo, Inbursa report\u00f3 una disminuci\u00f3n del 11 por ciento en la utilidad neta de 2025, impulsada por impactos no recurrentes y no monetarios en los ingresos operativos relacionados con el mercado<\/p>\n<p class=\"nota-justify\">En cuanto a la capitalizaci\u00f3n se mantuvo como una fortaleza crediticia clave, con los bancos reportando m\u00e9tricas de capital por encima de los requerimientos regulatorios.<\/p>\n<p class=\"nota-justify\">Al cierre de 2025, el \u00edndice de capital total regulatorio de BBVA M\u00e9xico fue de 20.2 por ciento, el de Banorte de 20.1 por ciento, el de Inbursa de 23.6 por ciento y el de Santander de 18.5 por ciento.<\/p>\n<p class=\"nota-justify\">Para el sector bancario, Fitch espera un crecimiento de los pr\u00e9stamos de un solo d\u00edgito en 2026 en medio del crecimiento moderado de la econom\u00eda mexicana.<\/p>\n<p class=\"nota-justify\">\u201cLos pr\u00e9stamos corporativos y comerciales se quedar\u00e1n rezagados y seguir\u00e1n siendo sensibles a la relaci\u00f3n comercial con Estados Unidos, mientras que los pr\u00e9stamos al consumo deber\u00edan liderar\u201d, coment\u00f3.<\/p>\n<p class=\"nota-justify\">\u201cLa digitalizaci\u00f3n y la baja penetraci\u00f3n pueden respaldar el crecimiento, pero es poco probable que compensen materialmente los crecientes riesgos del entorno operativo\u201d, concluy\u00f3 Fitch.<\/p>\n<\/div>\n<\/div>\n<div class=\"notas-relacionadas\"><\/div>\n<div class=\"nota-tags\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los bancos m\u00e1s grandes del pa\u00eds registran rentabilidad, colchones de capital superiores a los que pide la regulaci\u00f3n y capacidad<\/p>\n","protected":false},"author":4,"featured_media":80332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2050],"tags":[],"class_list":["post-80331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/02\/BANC.jpg?fit=1200%2C805&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=80331"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/80332"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=80331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=80331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=80331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}