{"id":80334,"date":"2026-02-20T00:11:56","date_gmt":"2026-02-20T06:11:56","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=80334"},"modified":"2026-02-19T23:17:58","modified_gmt":"2026-02-20T05:17:58","slug":"repsol-proyecta-aumentar-50-la-produccion-de-petroleo-en-venezuela","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/02\/20\/repsol-proyecta-aumentar-50-la-produccion-de-petroleo-en-venezuela\/","title":{"rendered":"Repsol proyecta aumentar 50% la producci\u00f3n de petr\u00f3leo en Venezuela"},"content":{"rendered":"<div id=\"article-content-tts\" class=\"nota-contenido mb-5\">\n<div id=\"content_nitf\">\n<p class=\"nota-justify\">La energ\u00e9tica y petroqu\u00edmica espa\u00f1ola Repsol aumentar\u00e1 un 50% su producci\u00f3n de petr\u00f3leo en Venezuela en los pr\u00f3ximos 12 meses, declar\u00f3 el consejero delegado de la multinacional, Josu Jon Imaz.<\/p>\n<p class=\"nota-justify\">El pasado 13 de febrero, Estados Unidos concedi\u00f3 una licencia a Repsol, as\u00ed como a la estadunidense Chevron Corporation, las brit\u00e1nicas BP PLC y Shell PLC y la italiana Eni SpA, autorizando la reanudaci\u00f3n de su producci\u00f3n de petr\u00f3leo en Venezuela.<\/p>\n<p class=\"nota-justify\">\u00abTenemos la ambici\u00f3n y vemos amplio margen para alcanzar este objetivo de triplicar la producci\u00f3n en tres a\u00f1os. Pero creo que lo importante es centrarse en el corto plazo. Por lo tanto, estimamos un aumento del 50% en la producci\u00f3n de petr\u00f3leo en los pr\u00f3ximos 12 meses\u00bb, afirm\u00f3 Imaz en una conferencia de prensa.<\/p>\n<p class=\"nota-justify\">El empresario coment\u00f3 que la situaci\u00f3n en la rep\u00fablica latinoamericana es \u00abmucho mejor que hace dos meses\u00bb y agradeci\u00f3 \u00abel apoyo y la actitud\u00bb positiva de la Casa Blanca.<\/p>\n<p class=\"nota-justify\">\u00abCreo que se abre una nueva ventana, una nueva oportunidad para un futuro mejor. Y tambi\u00e9n, digamos, una mejor situaci\u00f3n para nuestro sector en ese pa\u00eds. Y creo que es momento de consolidar esta mejora, fortaleciendo la estabilidad social y el desarrollo econ\u00f3mico del pa\u00eds\u00bb, agreg\u00f3 Imaz, precisando que la empresa coopera de manera estrecha con las autoridades venezolanas.<\/p>\n<p class=\"nota-justify\">EU y Venezuela comenzaron un proceso para reiniciar las relaciones diplom\u00e1ticas luego de que Washington realizara un ataque a\u00e9reo el 3 de enero en Caracas para secuestrar al presidente Nicol\u00e1s Maduro, y a su esposa Cilia Flores, y de que el mandatario Donald Trump anunciara que su pa\u00eds se har\u00e1 cargo del petr\u00f3leo venezolano.<\/p>\n<\/div>\n<\/div>\n<div class=\"notas-relacionadas\"><\/div>\n<div class=\"nota-tags\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La energ\u00e9tica y petroqu\u00edmica espa\u00f1ola Repsol aumentar\u00e1 un 50% su producci\u00f3n de petr\u00f3leo en Venezuela en los pr\u00f3ximos 12 meses,<\/p>\n","protected":false},"author":4,"featured_media":80335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2050],"tags":[],"class_list":["post-80334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/02\/RPSL.jpg?fit=1200%2C818&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=80334"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/80335"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=80334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=80334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=80334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}