{"id":80409,"date":"2026-02-21T00:15:07","date_gmt":"2026-02-21T06:15:07","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=80409"},"modified":"2026-02-20T22:59:17","modified_gmt":"2026-02-21T04:59:17","slug":"ezln-realiza-protestas-en-chiapas-durante-jornadas-por-justicia-para-samir-flores","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/02\/21\/ezln-realiza-protestas-en-chiapas-durante-jornadas-por-justicia-para-samir-flores\/","title":{"rendered":"EZLN realiza protestas en Chiapas durante Jornadas por justicia para Samir Flores"},"content":{"rendered":"<p class=\"nota-justify\">Con actos de protesta realizados en los Caracoles ubicados en Oventik, Morelia, La Garrucha y La Realidad, cientos de bases de apoyo del Ej\u00e9rcito Zapatista de Liberaci\u00f3n Nacional (EZLN), participaron en las llamadas Jornadas Nacionales e Internacionales Justicia para Samir y autodeterminaci\u00f3n para los pueblos, que tendr\u00e1n lugar del 19 al 22 de este mes en diferentes partes de M\u00e9xico y de otros pa\u00edses.<\/p>\n<p class=\"nota-justify\">\u00abSamir es un s\u00edmbolo de resistencia y rebeld\u00eda para los que luchamos en M\u00e9xico y el mundo, y los que no se organizan y no luchan, \u00bfentonces qu\u00e9 y hasta cu\u00e1ndo? No esperemos que la justicia la hagan los de arriba, los de la pir\u00e1mide, los del poder; la justicia vendr\u00e1 desde abajo, de los pueblos organizados\u201d, afirmaron.<\/p>\n<p class=\"nota-justify\">En un video difundido por el EZLN con im\u00e1genes de los actos efectuados durante la madrugada en los Caracoles mencionados, se observa a cientos de zapatistas con velas y pancartas alusivas a Samir, asesinado el 20 de febrero de 2019, afuera de su casa en Morelos.<\/p>\n<p class=\"nota-justify\">Las Jornadas Nacionales e Internacionales Justicia para Samir y autodeterminaci\u00f3n para los pueblos, a realizarse \u201cen cada uno de sus territorios\u201d, fueron convocadas por el EZLN, el Frente de Pueblos en Defensa de la Tierra y el Agua Morelos, Puebla, Tlaxcala y el Congreso Nacional Ind\u00edgena.<\/p>\n<p class=\"nota-justify\">\u201cLa vida y la sangre del compa\u00f1ero Samir no fue en vano\u201d, corearon los manifestantes.<\/p>\n<p class=\"nota-justify\">\u201cVivan los pueblos que defienden a la madre tierra\u201d, \u201cviva el compa\u00f1ero Samir\u201d, \u201cvivan los pueblos que resisten en M\u00e9xico y el mundo\u201d, \u201cviva el Congreso Nacional Ind\u00edgena\u201d, agregaron.<\/p>\n<p class=\"nota-justify\">\u201cSamir entreg\u00f3 su sangre y su vida por defender la madre tierra\u201d, \u201cel ejemplo del compa\u00f1ero Samir sigue y sigue\u201d, \u201ccon la sangre y la vida del compa\u00f1ero Samir, se detuvo una tormenta para nosotros\u201d, \u201ces tiempo de resistencia y rebeld\u00eda para los que luchan y los que no se organizan ni luchan, \u00bfentonces qu\u00e9?\u201d, expresaron.<\/p>\n<p class=\"nota-justify\">Los zapatistas reiteraron que \u201cestamos aqu\u00ed para recordar el cruel asesinato del compa\u00f1ero Samir y los malos gobiernos los han dejado impune porque hasta la fecha no hay justicia. Por eso decimos que la mejor forma de recordar al compa\u00f1ero Samir y a todos y todas los que han sido asesinado se seguir su ejemplo de lucha\u201d.<\/p>\n<p class=\"nota-justify\">Propusieron \u201cya no perder m\u00e1s tiempo en pedirle justicia a los que est\u00e1n arriba, los que dicen que tienen el poder\u201d.<\/p>\n<p class=\"nota-justify\">Las agrupaciones que convocaron a las Jornadas, recordaron a Samir Flores como defensor del territorio, comunicador ind\u00edgena y referente de lucha para muchas de nosotras y nosotros, por su tenacidad, humildad, creatividad, dignidad y compromiso.<\/p>\n<p class=\"nota-justify\">Manifestaron que \u201cfrente a la estrategia local y global de terror, saqueo y destrucci\u00f3n, los pueblos de M\u00e9xico y del mundo hemos luchado con memoria, rebeld\u00eda y organizaci\u00f3n para defender y fortalecer nuestra autodeterminaci\u00f3n, ese derecho natural e inalienable de los pueblos de decidir sobre su destino, las bases que occidente llama derecho internacional\u201d.<\/p>\n<p class=\"nota-justify\">Sostuvieron que \u201clos intereses de poderes quieren dominar y socavar la vida como la conocemos, apropi\u00e1ndose del petr\u00f3leo, litio, oro, agua y todos los bienes naturales que existen en la tierra y que los pueblos los hemos cuidado y preservado por siglos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con actos de protesta realizados en los Caracoles ubicados en Oventik, Morelia, La Garrucha y La Realidad, cientos de bases<\/p>\n","protected":false},"author":4,"featured_media":80410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30],"tags":[],"class_list":["post-80409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/02\/ELSAM.jpg?fit=1200%2C903&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=80409"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/80410"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=80409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=80409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=80409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}