{"id":81953,"date":"2026-03-23T00:18:44","date_gmt":"2026-03-23T06:18:44","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=81953"},"modified":"2026-03-22T22:50:47","modified_gmt":"2026-03-23T04:50:47","slug":"hoduras-y-estados-unidos-acuerdan-alianza-contra-el-narcotrafico-en-america-latina","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/03\/23\/hoduras-y-estados-unidos-acuerdan-alianza-contra-el-narcotrafico-en-america-latina\/","title":{"rendered":"Hoduras y Estados Unidos acuerdan alianza contra el narcotr\u00e1fico en Am\u00e9rica Latina"},"content":{"rendered":"<p class=\"nota-justify\">Honduras se comprometi\u00f3 este domingo a trabajar con las agencias de seguridad de Estados Unidos para luchar contra el narcotr\u00e1fico, tras una reuni\u00f3n entre Kristi Noem, enviada especial de Washington para una alianza de seguridad en Am\u00e9rica Latina, y el presidente hondure\u00f1o, Nasry Asfura.<\/p>\n<p class=\"nota-justify\">A principios de marzo, el presidente de Estados Unidos, Donald Trump, anunci\u00f3 una alianza con algunos pa\u00edses latinoamericanos para \u00abdestruir\u00bb a los c\u00e1rteles de la droga, durante una cumbre en Florida a la que acudi\u00f3 Asfura, entre otros mandatarios derechistas de la regi\u00f3n.<\/p>\n<p class=\"nota-justify\">Honduras es uno de los pa\u00edses m\u00e1s violentos de Centroam\u00e9rica, donde operan las pandillas Mara Salvatrucha y Barrio 18, protagonistas de la mayor parte de los homicidios y del narcotr\u00e1fico en el pa\u00eds, y declaradas organizaciones terroristas por Washington.<\/p>\n<p class=\"nota-justify\">\u00abHa sido una reuni\u00f3n (&#8230;) con muy buena receptividad\u00bb donde se abordaron temas como migraci\u00f3n y seguridad para \u00abtrabajar juntos y hacer una Am\u00e9rica m\u00e1s pr\u00f3spera\u00bb, dijo Asfura tras reunirse con Noem en la Casa Presidencial, en Tegucigalpa.<\/p>\n<p class=\"nota-justify\">Durante la comparecencia de Asfura no se permitieron preguntas a la prensa, mientras que Noem abandon\u00f3 el lugar sin dar declaraciones.<\/p>\n<p class=\"nota-justify\">\u00abGarantizamos que vamos a poner todo nuestro empe\u00f1o para poder trabajar conjuntamente\u00bb y coordinadamente \u00abentre nuestras instituciones nacionales\u00bb y \u00ablas diferentes agencias federales de los Estados Unidos para combatir m\u00e1s eficientemente el crimen\u00bb, afirm\u00f3 el ministro de Seguridad, Gerson Vel\u00e1squez.<\/p>\n<p class=\"nota-justify\">Se abordaron \u00abtemas estrat\u00e9gicos\u00bb en el marco de la iniciativa de Trump, conocida como \u00abEscudo de las Am\u00e9ricas\u00bb, incluyendo \u00abel fortalecimiento de la ciberseguridad, la lucha frontal contra el narcotr\u00e1fico y el crimen organizado\u00bb, indic\u00f3 el gobierno hondure\u00f1o en un comunicado.<\/p>\n<p class=\"nota-justify\">Tambi\u00e9n se acord\u00f3, seg\u00fan la nota, el reforzamiento de la polic\u00eda y el ej\u00e9rcito hondure\u00f1o \u00abmediante asistencia t\u00e9cnica especializada\u00bb.<\/p>\n<p class=\"nota-justify\">Noem, una de las principales figuras de la ofensiva del gobierno de Estados Unidos contra la inmigraci\u00f3n, fue despedida como secretaria de Seguridad Nacional por Trump, que le asign\u00f3 coordinar esta alianza sobre seguridad con pa\u00edses latinoamericanos, donde tambi\u00e9n est\u00e1n El Salvador, Argentina, Costa Rica, Ecuador y Panam\u00e1, entre otros.<\/p>\n<p class=\"nota-justify\">En Honduras, el oficialismo prepara una reforma penal para endurecer las leyes contra el crimen organizado, en una Am\u00e9rica Latina donde algunos gobiernos buscan adoptar elementos de la lucha antipandillas del mandatario salvadore\u00f1o, Nayib Bukele, muy cuestionado por organizaciones de defensa de los derechos humanos.<\/p>\n<p class=\"nota-justify\">Asfura recibi\u00f3 durante la campa\u00f1a el firme apoyo de Trump. A las puertas de la votaci\u00f3n, el republicano tambi\u00e9n indult\u00f3 al ex mandatario conservador y copartidario de Asfura, Juan Orlando Hern\u00e1ndez, quien cumpl\u00eda una pena de 45 a\u00f1os de c\u00e1rcel por narcotr\u00e1fico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Honduras se comprometi\u00f3 este domingo a trabajar con las agencias de seguridad de Estados Unidos para luchar contra el narcotr\u00e1fico,<\/p>\n","protected":false},"author":4,"featured_media":81954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-81953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/03\/VERSU.jpg?fit=1200%2C865&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/81953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=81953"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/81953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/81954"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=81953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=81953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=81953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}