{"id":82840,"date":"2026-04-08T21:52:39","date_gmt":"2026-04-09T03:52:39","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=82840"},"modified":"2026-04-08T21:52:39","modified_gmt":"2026-04-09T03:52:39","slug":"concierto-para-dos-fagotes-de-vanhal-en-velada-clasica-osx","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/04\/08\/concierto-para-dos-fagotes-de-vanhal-en-velada-clasica-osx\/","title":{"rendered":"Concierto para dos fagotes de Vanhal en velada \u201ccl\u00e1sica\u201d OSX"},"content":{"rendered":"<ul>\n<li>Rex Gulson, fagot principal OSX, se despide como solista<\/li>\n<li>Armando Salgado, fagot asistente OSX, solista<\/li>\n<li>Martin Lebel, director titular\n<p>Xalapa, Ver. 07 de abril de 2026. La Orquesta Sinf\u00f3nica de Xalapa abre su actividad musical de abril, presentando el tradicional concierto \u201ccl\u00e1sico\u201d con dos de los mayores exponentes de dicho movimiento musical: Johann Baptist Vanhal, y su Concierto para dos fagotes y orquesta; y Joseph Haydn, con su Sinfon\u00eda n.\u00b0 102. Adem\u00e1s, la Sinfon\u00eda n.\u00b0 3 de Franz Schubert.<br \/>\nCon la participaci\u00f3n como solistas de: Rex Gulson, fagot principal OSX, en su \u00faltima presentaci\u00f3n con la Sinf\u00f3nica de Xalapa tras 40 a\u00f1os de trayectoria; y Armando Salgado, fagot asistente OSX. Bajo la batuta de Martin Lebel, director titular.<br \/>\nEste concierto se realizar\u00e1 el viernes 10 de abril de 2026 a las 20:00 h.<\/li>\n<\/ul>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-82842\" src=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/04\/Rex-Gulson.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/04\/Rex-Gulson.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/04\/Rex-Gulson.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/04\/Rex-Gulson.jpg?w=960&amp;ssl=1 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Jan K\u0159titel Vanhal, originario de Bohemia y con nombres germanizados debido a la suspicacia del mundo cultural de entonces hacia los m\u00fasicos de Bohemia, produjo un buen n\u00famero de conciertos, aunque es el Concierto para dos fagotes y orquesta uno de los que m\u00e1s destaca de esta producci\u00f3n. Sus tres movimientos tienen la estructura en forma sonata, y es una pieza fundamental para este instrumento de aliento. Interpretado por los solistas OSX: Rex Gulson, y Armando Salgado.<\/p>\n<p>&nbsp;<\/p>\n<p>Joseph Haydn, tambi\u00e9n conocido como el padre de la sinfon\u00eda, creo su Sinfon\u00eda n.\u00b0 102, concebida para dos flautas, dos oboes, dos fagotes, dos cornos, dos trompetas, timbales y cuerdas. Fue estrenada en Londres el 2 de febrero de 1795, y su segundo movimiento es an\u00e1logo al Adagio de un tr\u00edo para piano compuesto por el mismo Haydn en 1794.<\/p>\n<p>&nbsp;<\/p>\n<p>En 1815, Schubert con 18 a\u00f1os de edad, trabajando a tiempo completo, y tomando clases de composici\u00f3n dos veces a la semana con Antonio Salieri, se las arregl\u00f3 para componer m\u00e1s de las 200 obras. Su Tercera Sinfon\u00eda es notablemente concisa, y m\u00e1s corta que las dos primeras, pero tambi\u00e9n presagia ideas que expandir\u00edan la escala de la sinfon\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p>Rex Lennes Gulson, solista OSX, es fagotista originario de Illinois, Estados Unidos. Estudi\u00f3 su Licenciatura y Maestr\u00eda en Artes en la Universidad de Iowa, con el profesor de fagot Ronald Tyree. En 1986 se integr\u00f3 a la Orquesta Sinf\u00f3nica de Xalapa como fagotista asistente y a partir de 2009 es el fagotista principal de la misma. Se ha presentado como solista y ha ofrecido recitales en diversas ocasiones.<\/p>\n<p>En 2004 termin\u00f3 su Doctorado en Indiana University gracias al apoyo que recibi\u00f3 de la Universidad Veracruzana y a la Beca Chancellor\u00b4s Fellowship de esa instituci\u00f3n norteamericana. Se ha mantenido activo en los \u00faltimos a\u00f1os ejecutando el fagot barroco con el Ensamble Galante ofreciendo conciertos en M\u00e9xico y en el extranjero. En el campo de la docencia ha sido profesor de fagot en la Facultad de M\u00fasica de la Universidad Veracruzana desde 1988 y en el Instituto Superior de M\u00fasica del Estado de Veracruz (ISMEV) de la Secretar\u00eda de Educaci\u00f3n de Veracruz (SEV) de 2005 a 2024.<\/p>\n<p>&nbsp;<\/p>\n<p>Armando Salgado, solista OSX, estudi\u00f3 la Licenciatura en M\u00fasica en la Facultad de M\u00fasica de la UV bajo la tutela del doctor Rex Gulson. Realiz\u00f3 estudios de perfeccionamiento t\u00e9cnico en la Universidad de la Ciudad de Viena, Austria con el Profesor Marcelo Padilla, as\u00ed como estudios de maestr\u00eda en la Universidad Internacional de la Rioja en Pedagog\u00eda Musical. En 2010 obtuvo el primer lugar en el Concurso Nacional de Fagot organizado por la escuela de m\u00fasica Ollin Yoliztli, y el primer lugar en el concurso de m\u00fasica de c\u00e1mara del Festival de M\u00fasica de C\u00e1mara Aguascalientes. En 2008 ingres\u00f3 como miembro de fila de la secci\u00f3n de fagotes de la OSX y desde 2011 se desempe\u00f1a como fagotista asistente de secci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Puedes comprar tus boletos en l\u00ednea en www.orquestasinfonicadexalapa.com, Tienda UV, Tienda UV Museo de Antropolog\u00eda y Taquilla Tlaqn\u00e1.<\/p>\n<p>Correo electr\u00f3nico: <a href=\"mailto:mercadotecnia.osx@gmail.com\">mercadotecnia.osx@gmail.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rex Gulson, fagot principal OSX, se despide como solista Armando Salgado, fagot asistente OSX, solista Martin Lebel, director titular Xalapa,<\/p>\n","protected":false},"author":4,"featured_media":82841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[474,30],"tags":[],"class_list":["post-82840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/04\/Armando-Salgado-scaled.jpg?fit=1707%2C2560&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/82840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=82840"}],"version-history":[{"count":0,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/82840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/82841"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=82840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=82840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=82840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}