{"id":84332,"date":"2026-05-09T00:20:02","date_gmt":"2026-05-09T06:20:02","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=84332"},"modified":"2026-05-08T21:42:05","modified_gmt":"2026-05-09T03:42:05","slug":"cuba-ejercera-su-derecho-de-legitima-defensa-con-apoyo-masivo-del-pueblo-canciller-bruno-rodriguez","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/05\/09\/cuba-ejercera-su-derecho-de-legitima-defensa-con-apoyo-masivo-del-pueblo-canciller-bruno-rodriguez\/","title":{"rendered":"Cuba ejercer\u00e1 su derecho de leg\u00edtima defensa con apoyo masivo del pueblo: canciller Bruno Rodr\u00edguez"},"content":{"rendered":"<p class=\"nota-justify\">El canciller Bruno Rodr\u00edguez ratific\u00f3 que Cuba salvaguardar\u00e1 su independencia y afirm\u00f3 que \u00abejercer\u00e1 su derecho a la leg\u00edtima defensa hasta las \u00faltimas consecuencias, con el apoyo masivo y multitudinario del pueblo\u00bb, y afirm\u00f3 que no se han logrado avances en las conversaciones con Estados Unidos<\/p>\n<p class=\"nota-justify\">En una entrevista concedida al medio estadunidense ABC News, el ministro de Relaciones Exteriores fue claro: \u00abCuba no representa una amenaza para Estados Unidos: ni para su seguridad nacional, ni para su pol\u00edtica exterior, ni para su econom\u00eda, ni para el estilo de vida estadunidense\u00bb.<\/p>\n<p class=\"nota-justify\">\u00abParece que el gobierno de Estados Unidos ha elegido un camino peligroso; un camino que podr\u00eda derivar en consecuencias inimaginables, en una cat\u00e1strofe humanitaria, en un genocidio, en la p\u00e9rdida de vidas cubanas y de j\u00f3venes estadounidenses; tambi\u00e9n podr\u00eda conducir a un ba\u00f1o de sangre en Cuba\u00bb, dijo.<\/p>\n<p class=\"nota-justify\">Rodr\u00edguez expres\u00f3 que no se ha producido ning\u00fan avance en las conversaciones con Estados Unidos y desestim\u00f3 las recientes exigencias de la administraci\u00f3n de Donald Trump en materia de reformas pol\u00edticas y econ\u00f3micas. \u00abPuedo decirle que no veo ning\u00fan progreso\u00bb, subray\u00f3.<\/p>\n<p class=\"nota-justify\">El jefe de la diplomacia cubana reiter\u00f3 la disposici\u00f3n de di\u00e1logo \u00absobre una gran variedad de cuestiones bilaterales\u00bb, pero enfatiz\u00f3 que los temas relacionados con el sistema pol\u00edtico o los asuntos internos de Cuba \u00abno est\u00e1n sobre la mesa\u00bb.<\/p>\n<p class=\"nota-justify\">Rodr\u00edguez refut\u00f3 los falsos pretextos utilizados por la Casa Blanca de Donald Trump para justificar una eventual agresi\u00f3n militar contra Cuba, algo \u00abprohibido por el derecho internacional\u00bb, acot\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El canciller Bruno Rodr\u00edguez ratific\u00f3 que Cuba salvaguardar\u00e1 su independencia y afirm\u00f3 que \u00abejercer\u00e1 su derecho a la leg\u00edtima defensa<\/p>\n","protected":false},"author":4,"featured_media":84333,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-84332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/05\/NOSOYNI.webp?fit=1200%2C741&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/84332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=84332"}],"version-history":[{"count":1,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/84332\/revisions"}],"predecessor-version":[{"id":84334,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/84332\/revisions\/84334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/84333"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=84332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=84332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=84332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}