{"id":86823,"date":"2026-07-15T00:09:44","date_gmt":"2026-07-15T06:09:44","guid":{"rendered":"https:\/\/politicosaldesnudo.com.mx\/?p=86823"},"modified":"2026-07-14T23:35:48","modified_gmt":"2026-07-15T05:35:48","slug":"medidas-de-trump-retrasaron-o-cancelaron-proyectos-de-energia-limpia-de-83-mil-millones-de-dolares","status":"publish","type":"post","link":"https:\/\/politicosaldesnudo.com.mx\/index.php\/2026\/07\/15\/medidas-de-trump-retrasaron-o-cancelaron-proyectos-de-energia-limpia-de-83-mil-millones-de-dolares\/","title":{"rendered":"Medidas de Trump retrasaron o cancelaron proyectos de energ\u00eda limpia de 83 mil millones de d\u00f3lares"},"content":{"rendered":"<p class=\"nota-justify\">Las medidas del Gobierno de Estados Unidos, encabezado por Donald Trump, que redujeron el apoyo de su pa\u00eds a las energ\u00edas limpias han provocado la cancelaci\u00f3n o el retraso de inversiones por valor de 83 mil millones de d\u00f3lares en cientos de proyectos, seg\u00fan un reporte publicado por la coalici\u00f3n sindical y medioambiental BlueGreen Alliance.<\/p>\n<p class=\"nota-justify\">El reporte se dio a conocer mientras los l\u00edderes sindicales se preparaban para reunirse el martes con senadores estadunidenses para debatir sobre la mano de obra del sector de la energ\u00eda limpia.<\/p>\n<p class=\"nota-justify\">El an\u00e1lisis revel\u00f3 que 223 proyectos de fabricaci\u00f3n y energ\u00eda limpia, que representan una inversi\u00f3n de 82 mil 900 millones de d\u00f3lares y 111 mil 765 puestos de trabajo, se han estancado o han sido cancelados durante el segundo mandato de Trump.<\/p>\n<p class=\"nota-justify\">El an\u00e1lisis atribuy\u00f3 esta situaci\u00f3n al emblem\u00e1tico paquete de medidas fiscales y de gasto de Trump, que derog\u00f3 o recort\u00f3 los incentivos de la era Biden, as\u00ed como a otras medidas del Gobierno destinadas a reducir el apoyo federal a las energ\u00edas renovables y a los veh\u00edculos el\u00e9ctricos.<\/p>\n<p class=\"nota-justify\">\u00abLas cifras resultantes ilustran claramente la asombrosa p\u00e9rdida de inversi\u00f3n y de creaci\u00f3n de empleo que han provocado las pol\u00edticas de este Gobierno y del Congreso\u00bb, dijo en un comunicado Roxanne Johnson, vicepresidenta de investigaci\u00f3n de BlueGreen Alliance.<\/p>\n<p class=\"nota-justify\">Trump ha afirmado que las fuentes de energ\u00eda renovables, como la e\u00f3lica y la solar, son poco fiables y reciben subvenciones injustas.<\/p>\n<p class=\"nota-justify\">El reporte tambi\u00e9n se\u00f1ala que los recortes de financiaci\u00f3n federal y los retrocesos normativos iniciados en 2025 han debilitado las protecciones laborales para los trabajadores de los sectores energ\u00e9tico e industrial.<\/p>\n<p class=\"nota-justify\">Entre los cambios citados figuran la derogaci\u00f3n de las normas de la Agencia de Protecci\u00f3n Medioambiental que regulan las industrias peligrosas y los retrasos en la aplicaci\u00f3n de una norma sobre la exposici\u00f3n a la s\u00edlice destinada a proteger a los mineros del carb\u00f3n de la inhalaci\u00f3n de polvo de s\u00edlice, lo que, seg\u00fan el reporte, podr\u00eda contribuir a un resurgimiento de la llamada enfermedad del pulm\u00f3n negro.<\/p>\n<p class=\"nota-justify\">Por otra parte, el reporte se\u00f1ala que 3 mil 034 proyectos de los sectores manufacturero, energ\u00e9tico e industrial se enfrentan a requisitos m\u00e1s estrictos para acceder a los cr\u00e9ditos fiscales en virtud de la Gran Ley Hermosa (One Big Beautiful Bill Act) de Trump, lo que pone en riesgo una inversi\u00f3n estimada de 695 mil 200 millones de d\u00f3lares y casi 1.2 millones de puestos de trabajo previstos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las medidas del Gobierno de Estados Unidos, encabezado por Donald Trump, que redujeron el apoyo de su pa\u00eds a las<\/p>\n","protected":false},"author":4,"featured_media":86824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[],"class_list":["post-86823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2026\/07\/ATTRA.webp?fit=1200%2C801&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/86823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=86823"}],"version-history":[{"count":1,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/86823\/revisions"}],"predecessor-version":[{"id":86825,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/86823\/revisions\/86825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media\/86824"}],"wp:attachment":[{"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=86823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=86823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicosaldesnudo.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=86823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}